{"id":8193,"date":"2022-06-16T22:02:40","date_gmt":"2022-06-17T04:02:40","guid":{"rendered":"http:\/\/nmcontemporaneo.com\/beta\/?page_id=8193"},"modified":"2025-06-21T01:42:29","modified_gmt":"2025-06-21T07:42:29","slug":"angel-ricardo-rios","status":"publish","type":"page","link":"https:\/\/nmcontemporaneo.com\/en\/catalogue\/paintings\/angel-ricardo-rios-en\/","title":{"rendered":"\u00c1ngel Ricardo R\u00edos"},"content":{"rendered":"<p style=\"text-align: center;\"><a href=\"..\/raul-cerrillo\/\">&lt;&lt; Previous<\/a> | <a href=\"\/catalogo\/todos-los-artistas\/\">All Artists<\/a> | <a href=\"https:\/\/nmcontemporaneo.com\/catalogo\/pintura\/otros-artistas\/claudia-gallegos\/\">Next &gt;&gt;<\/a><\/p>\n<div id=\"kad-wp-gallery152\" class=\"kad-wp-gallery gallery kt-gallery-column-3 init-isotope-intrinsic reinit-isotope kad-light-wp-gallery clearfix rowtight\" data-fade-in=\"1\" data-iso-selector=\".g_item\" data-iso-style=\"masonry\" data-iso-filter=\"false\"><div class=\"tcol-lg-4 tcol-md-4 tcol-sm-4 tcol-xs-6 tcol-ss-12 g_item\"><div class=\"grid_item kt_item_fade_in kad_gallery_fade_in gallery_item\"><a href=\"https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2024\/10\/dibujo-1-diptico.jpg\" data-rel=\"lightbox\" class=\"lightboxhover\"><div class=\"kt-intrinsic\" style=\"padding-bottom:74.31693989071%;\"><div itemprop=\"image\" itemscope itemtype=\"https:\/\/schema.org\/ImageObject\"><img loading=\"lazy\" decoding=\"async\" width=\"366\" height=\"272\" src=\"https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2024\/10\/dibujo-1-diptico-366x272.jpg\" srcset=\"https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2024\/10\/dibujo-1-diptico-366x272.jpg 366w, https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2024\/10\/dibujo-1-diptico-300x223.jpg 300w, https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2024\/10\/dibujo-1-diptico-768x570.jpg 768w, https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2024\/10\/dibujo-1-diptico-732x544.jpg 732w, https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2024\/10\/dibujo-1-diptico.jpg 900w\" sizes=\"auto, (max-width: 366px) 100vw, 366px\" data-caption=\"Dibujo I (D\u00edptico), Carb\u00f3n, pastel sobre cartulina.\n100 x 140 cm, 2016\" class=\"light-dropshaddow\" itemprop=\"contentUrl\" alt=\"\"><meta itemprop=\"url\" content=\"https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2024\/10\/dibujo-1-diptico-366x272.jpg\"><meta itemprop=\"width\" content=\"366px\"><meta itemprop=\"height\" content=\"272px\"><\/div><\/div><div class=\"caption kad_caption\"><div class=\"kad_caption_inner\">Dibujo I (D\u00edptico), Carb\u00f3n, pastel sobre cartulina.\n100 x 140 cm, 2016<\/div><\/div><\/a><\/div><\/div><div class=\"tcol-lg-4 tcol-md-4 tcol-sm-4 tcol-xs-6 tcol-ss-12 g_item\"><div class=\"grid_item kt_item_fade_in kad_gallery_fade_in gallery_item\"><a href=\"https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2024\/10\/dibujo-2-diptico.jpg\" data-rel=\"lightbox\" class=\"lightboxhover\"><div class=\"kt-intrinsic\" style=\"padding-bottom:71.311475409836%;\"><div itemprop=\"image\" itemscope itemtype=\"https:\/\/schema.org\/ImageObject\"><img loading=\"lazy\" decoding=\"async\" width=\"366\" height=\"261\" src=\"https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2024\/10\/dibujo-2-diptico-366x261.jpg\" srcset=\"https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2024\/10\/dibujo-2-diptico-366x261.jpg 366w, https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2024\/10\/dibujo-2-diptico-300x214.jpg 300w, https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2024\/10\/dibujo-2-diptico-768x548.jpg 768w, https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2024\/10\/dibujo-2-diptico-732x522.jpg 732w, https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2024\/10\/dibujo-2-diptico.jpg 900w\" sizes=\"auto, (max-width: 366px) 100vw, 366px\" data-caption=\"Dibujo 2 (D\u00edptico),\nCarb\u00f3n, pastel sobre cartulina.\n100 x 140 cm, 2016\" class=\"light-dropshaddow\" itemprop=\"contentUrl\" alt=\"\"><meta itemprop=\"url\" content=\"https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2024\/10\/dibujo-2-diptico-366x261.jpg\"><meta itemprop=\"width\" content=\"366px\"><meta itemprop=\"height\" content=\"261px\"><\/div><\/div><div class=\"caption kad_caption\"><div class=\"kad_caption_inner\">Dibujo 2 (D\u00edptico),\nCarb\u00f3n, pastel sobre cartulina.\n100 x 140 cm, 2016<\/div><\/div><\/a><\/div><\/div><div class=\"tcol-lg-4 tcol-md-4 tcol-sm-4 tcol-xs-6 tcol-ss-12 g_item\"><div class=\"grid_item kt_item_fade_in kad_gallery_fade_in gallery_item\"><a href=\"https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2024\/10\/dibujo-3.jpg\" data-rel=\"lightbox\" class=\"lightboxhover\"><div class=\"kt-intrinsic\" style=\"padding-bottom:137.43169398907%;\"><div itemprop=\"image\" itemscope itemtype=\"https:\/\/schema.org\/ImageObject\"><img loading=\"lazy\" decoding=\"async\" width=\"366\" height=\"503\" src=\"https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2024\/10\/dibujo-3-366x503.jpg\" srcset=\"https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2024\/10\/dibujo-3-366x503.jpg 366w, https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2024\/10\/dibujo-3-218x300.jpg 218w, https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2024\/10\/dibujo-3.jpg 655w\" sizes=\"auto, (max-width: 366px) 100vw, 366px\" data-caption=\"Dibujo 3.\nCarb\u00f3n, pastel acr\u00edlico sobre cartulina.\n100 x 70 cm, 2022\" class=\"light-dropshaddow\" itemprop=\"contentUrl\" alt=\"\"><meta itemprop=\"url\" content=\"https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2024\/10\/dibujo-3-366x503.jpg\"><meta itemprop=\"width\" content=\"366px\"><meta itemprop=\"height\" content=\"503px\"><\/div><\/div><div class=\"caption kad_caption\"><div class=\"kad_caption_inner\">Dibujo 3.\nCarb\u00f3n, pastel acr\u00edlico sobre cartulina.\n100 x 70 cm, 2022<\/div><\/div><\/a><\/div><\/div><div class=\"tcol-lg-4 tcol-md-4 tcol-sm-4 tcol-xs-6 tcol-ss-12 g_item\"><div class=\"grid_item kt_item_fade_in kad_gallery_fade_in gallery_item\"><a href=\"https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2024\/10\/dibujo-4.jpg\" data-rel=\"lightbox\" class=\"lightboxhover\"><div class=\"kt-intrinsic\" style=\"padding-bottom:137.70491803279%;\"><div itemprop=\"image\" itemscope itemtype=\"https:\/\/schema.org\/ImageObject\"><img loading=\"lazy\" decoding=\"async\" width=\"366\" height=\"504\" src=\"https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2024\/10\/dibujo-4-366x504.jpg\" srcset=\"https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2024\/10\/dibujo-4-366x504.jpg 366w, https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2024\/10\/dibujo-4-218x300.jpg 218w, https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2024\/10\/dibujo-4.jpg 600w\" sizes=\"auto, (max-width: 366px) 100vw, 366px\" data-caption=\"Dibujo 4.\nCarb\u00f3n, pastel acr\u00edlico sobre cartulina.\n100 x 70 cm, 2022\" class=\"light-dropshaddow\" itemprop=\"contentUrl\" alt=\"\"><meta itemprop=\"url\" content=\"https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2024\/10\/dibujo-4-366x504.jpg\"><meta itemprop=\"width\" content=\"366px\"><meta itemprop=\"height\" content=\"504px\"><\/div><\/div><div class=\"caption kad_caption\"><div class=\"kad_caption_inner\">Dibujo 4.\nCarb\u00f3n, pastel acr\u00edlico sobre cartulina.\n100 x 70 cm, 2022<\/div><\/div><\/a><\/div><\/div><div class=\"tcol-lg-4 tcol-md-4 tcol-sm-4 tcol-xs-6 tcol-ss-12 g_item\"><div class=\"grid_item kt_item_fade_in kad_gallery_fade_in gallery_item\"><a href=\"https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2024\/10\/el-parque-almendares.jpg\" data-rel=\"lightbox\" class=\"lightboxhover\"><div class=\"kt-intrinsic\" style=\"padding-bottom:58.196721311475%;\"><div itemprop=\"image\" itemscope itemtype=\"https:\/\/schema.org\/ImageObject\"><img loading=\"lazy\" decoding=\"async\" width=\"366\" height=\"213\" src=\"https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2024\/10\/el-parque-almendares-366x213.jpg\" srcset=\"https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2024\/10\/el-parque-almendares-366x213.jpg 366w, https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2024\/10\/el-parque-almendares-300x175.jpg 300w, https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2024\/10\/el-parque-almendares-768x448.jpg 768w, https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2024\/10\/el-parque-almendares-732x426.jpg 732w, https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2024\/10\/el-parque-almendares.jpg 1000w\" sizes=\"auto, (max-width: 366px) 100vw, 366px\" data-caption=\"El parque Almendares no es lo que era antes.\n\u00d3leo sobre tela, 2021\n155 x 250 cm\" class=\"light-dropshaddow\" itemprop=\"contentUrl\" alt=\"\"><meta itemprop=\"url\" content=\"https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2024\/10\/el-parque-almendares-366x213.jpg\"><meta itemprop=\"width\" content=\"366px\"><meta itemprop=\"height\" content=\"213px\"><\/div><\/div><div class=\"caption kad_caption\"><div class=\"kad_caption_inner\">El parque Almendares no es lo que era antes.\n\u00d3leo sobre tela, 2021\n155 x 250 cm<\/div><\/div><\/a><\/div><\/div><div class=\"tcol-lg-4 tcol-md-4 tcol-sm-4 tcol-xs-6 tcol-ss-12 g_item\"><div class=\"grid_item kt_item_fade_in kad_gallery_fade_in gallery_item\"><a href=\"https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2024\/10\/tepies-desnudo.jpg\" data-rel=\"lightbox\" class=\"lightboxhover\"><div class=\"kt-intrinsic\" style=\"padding-bottom:95.628415300546%;\"><div itemprop=\"image\" itemscope itemtype=\"https:\/\/schema.org\/ImageObject\"><img loading=\"lazy\" decoding=\"async\" width=\"366\" height=\"350\" src=\"https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2024\/10\/tepies-desnudo-366x350.jpg\" srcset=\"https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2024\/10\/tepies-desnudo-366x350.jpg 366w, https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2024\/10\/tepies-desnudo-300x287.jpg 300w, https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2024\/10\/tepies-desnudo-768x735.jpg 768w, https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2024\/10\/tepies-desnudo-732x700.jpg 732w, https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2024\/10\/tepies-desnudo.jpg 940w\" sizes=\"auto, (max-width: 366px) 100vw, 366px\" data-caption=\"Tapies desnudo.\n\u00d3leo sobre tela.\n206 x 204 cm. 2021.\" class=\"light-dropshaddow\" itemprop=\"contentUrl\" alt=\"\"><meta itemprop=\"url\" content=\"https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2024\/10\/tepies-desnudo-366x350.jpg\"><meta itemprop=\"width\" content=\"366px\"><meta itemprop=\"height\" content=\"350px\"><\/div><\/div><div class=\"caption kad_caption\"><div class=\"kad_caption_inner\">Tapies desnudo.\n\u00d3leo sobre tela.\n206 x 204 cm. 2021.<\/div><\/div><\/a><\/div><\/div><\/div>\n<p style=\"font-weight: 400;\">Angel Ricardo Rios (1965), a Cuban artist who lives in Mexico since 1991. Studied arts at the Faculty of Fine Arts in Havana, also has a masters in sculpture. Leading role in the national and international art sphere, through the galleries, Nina Menocal, MITO and Terreno Valdio, in Mexico City. Jacobo Kapio and Klaus Steinmetz in Costa Rica, El Museo Gallery in Colombia, Fernando Pradilla and Angel Romero in Madrid and Sevil Sert Gallery in Istanbul.<\/p>\n<p style=\"font-weight: 400;\">The artist, expresses the culture of excess through his art, with squandered paint among the canvasses, not afraid to mix shapes and colors, with centrifugal movement, between figurative and abstract large- format pieces: an outrageously seductive intent, through stimulating and corporeal quality of the material.<\/p>\n<p style=\"font-weight: 400;\">&#8220;The pleasure was restored in its own right. To this could be called the seduction of material: smell, touch, sensuality, racking of pigments, gymnastics &#8220;&#8230;<\/p>\n\n<div class=\"sp-wrap sp-wrap-default\">\n<div class=\"sp-head\" title=\"Expand\">\nCurriculum Vitae\n<\/div>\n<div class=\"sp-body folded\">\n<p><strong>\u00c1ngel Ricardo R\u00edos<\/strong><\/p>\n<p><strong>ESTUDIES<\/strong><br \/>\n1989 Faculty of Fine Arts of Havana, Cuba.<br \/>\n1984 National School of Art San Alejandro, Havana, Cuba.<\/p>\n<p><strong>SOLO EXHIBITIONS<\/strong><br \/>\n2015 LA Art Show. Los Angeles, California. Special project for contemporary art fair.<br \/>\n2014 Building Bridges. Art Exchange, Santa Monica, USA.<br \/>\n2012 Wynwood Exhibition Center &#8211; Miami Florida USA.<br \/>\n2011 Gallery Terreno Bald\u00edo, Mexico DF<br \/>\n2010 Objects of desire. Fernando Pradilla Gallery. Madrid, Spain.<br \/>\n2009 Nomads Sculptures. Havana Biennial UNEAC. Havana, Cuba.<br \/>\n2008 ART inc. GALLERY Guayaquil, Ecuador.<br \/>\nProject: ESCULTURAS NOMADAS. Museum SHCP. Mexico DF.<br \/>\nCultural of Spain in Mexico. Mexico DF.<br \/>\n2007 Gallery SEVIL SERT Istanbul, Turkey<br \/>\n2001 This is not a chair. Havana Gallery. Havana, Cuba.<br \/>\n2000 James Carpio Gallery. San Jose, Costa Rica.<br \/>\n1999 Angel Romero Gallery. Madrid, Spain.<br \/>\nFreites-Revilla Gallery. Coral Gables, Florida. USA.<br \/>\nThe source. Tower of the Winds. Mexico DF.<br \/>\n1998 Domestic Sculpture. Nina Menocal Gallery. Mexico DF.<br \/>\n1994 The comfortable home. Nina Menocal Gallery. Mexico DF.<br \/>\n1984 Jos\u00e9 Mart\u00ed National Library. Havana, Cuba.<\/p>\n<p><strong>GROUP EXHIBITIONS<\/strong><br \/>\nBUGATTI International Prize 2014, Issue 55 (group show).<br \/>\n2013 Crossover. Museum of the Ministry of Foreign Affairs. Mexico DF.<br \/>\n2012 Contemporary Mexican Art. Egypt Palace Cultural Center. Oeiras, Portugal.<br \/>\nCrossing Borders: New items for the domestic space. Zafra Design &amp; Art, Mexico City.<br \/>\nAQUA12 Contemporary Art Fair. Miami, USA.<br \/>\n2010 ZONA MACO 2010, Contemporary Art Fair. Fernando Pradilla Gallery. Mexico.<br \/>\nART MADRID, Fernando Pradilla Gallery. Madrid, Spain.<br \/>\nPortugal 10. International Art Biennale. Portimao, Portugal.<br \/>\n2009 Fourth Biennial of Visual Arts Yucatan, Mexico.<br \/>\nContemporary Art 2009, annual auction (sixteen group)<br \/>\nAuction of Contemporary Art Museum of Anthropology. Mexico DF.<br \/>\n2008 Project. Giant and the City. Miami, Florida. USA.<br \/>\n2007 ARTEROTICO, The origin of the world. Puebla, Mexico.<br \/>\nMuseum of the Ministry of Finance. Mexico DF.<br \/>\n2005 ARCO 05 Contemporary Art Fair. Madrid, Spain.<br \/>\n2003 Seventh Biennial of Havana. Havana, Cuba.<br \/>\nBiennial Monterrey, Mexico.<br \/>\n2002 First Biennial of Visual Arts in Yucatan. Merida, Mexico.<br \/>\nXI Biennial &#8220;Rufino Tamayo&#8221;, Mexico DF<br \/>\n2001 Contemporary Art Fair Guadalajara. Jalisco, Mexico.<br \/>\nVIDEO-zapping Video installations. University of Guanajuato, Mexico.<br \/>\nContemporary Art Fair, Gallery James Carpio. Caracas, Venezuela.<br \/>\nMIAMI ART. Gallery James Carpio. USA.<br \/>\n2000 erogenous. Carrillo Gil Museum. Mexico DF.<br \/>\nKaleidoscope. Contemporary Bancomex-Sinudetes. Mexico DF.<br \/>\nMIAMI ART. Nina Menocal Gallery. USA.<br \/>\n1999 Artists Collective. Nina Menocal Gallery. Mexico DF.<br \/>\nOn paper, Nina Menocal Gallery. Mexico DF.<br \/>\n1998 Salon Bancomer, Mexico, DF<br \/>\nBienal Rufino Tamayo. Mexico DF.<br \/>\n1998 Sal\u00f3n Bancomer, M\u00e9xico, D.F.<br \/>\nBienal Rufino Tamayo. M\u00e9xico, D.F.<\/p>\n<div class=\"spdiv\">[collapse]<\/div>\n<\/div>\n<\/div>\n\n","protected":false},"excerpt":{"rendered":"<p>Angel Ricardo Rios, a Cuban artist who lives in Mexico since 1991. Studied arts at the Faculty of Fine Arts in Havana, also has a masters in sculpture.<\/p>\n","protected":false},"author":25,"featured_media":10220,"parent":590,"menu_order":0,"comment_status":"open","ping_status":"closed","template":"page-fullwidth.php","meta":{"kt_blocks_editor_width":"","footnotes":""},"class_list":["post-8193","page","type-page","status-publish","has-post-thumbnail","hentry"],"_links":{"self":[{"href":"https:\/\/nmcontemporaneo.com\/en\/wp-json\/wp\/v2\/pages\/8193","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nmcontemporaneo.com\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/nmcontemporaneo.com\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/nmcontemporaneo.com\/en\/wp-json\/wp\/v2\/users\/25"}],"replies":[{"embeddable":true,"href":"https:\/\/nmcontemporaneo.com\/en\/wp-json\/wp\/v2\/comments?post=8193"}],"version-history":[{"count":3,"href":"https:\/\/nmcontemporaneo.com\/en\/wp-json\/wp\/v2\/pages\/8193\/revisions"}],"predecessor-version":[{"id":14272,"href":"https:\/\/nmcontemporaneo.com\/en\/wp-json\/wp\/v2\/pages\/8193\/revisions\/14272"}],"up":[{"embeddable":true,"href":"https:\/\/nmcontemporaneo.com\/en\/wp-json\/wp\/v2\/pages\/590"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/nmcontemporaneo.com\/en\/wp-json\/wp\/v2\/media\/10220"}],"wp:attachment":[{"href":"https:\/\/nmcontemporaneo.com\/en\/wp-json\/wp\/v2\/media?parent=8193"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}