{"id":6991,"date":"2014-01-13T22:20:08","date_gmt":"2014-01-14T04:20:08","guid":{"rendered":"http:\/\/nmcontemporaneo.com\/beta\/?p=6991"},"modified":"2025-06-20T01:02:29","modified_gmt":"2025-06-20T07:02:29","slug":"la-estetica-de-los-salvaje-2014","status":"publish","type":"post","link":"https:\/\/nmcontemporaneo.com\/en\/la-estetica-de-los-salvaje-2014\/","title":{"rendered":""},"content":{"rendered":"<p><a href=\"http:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/Estetica-de-lo-Salvaje.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-6993 size-large\" src=\"http:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/Estetica-de-lo-Salvaje-663x1024.jpg\" alt=\"Estetica de lo Salvaje\" width=\"663\" height=\"1024\" srcset=\"https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/Estetica-de-lo-Salvaje-663x1024.jpg 663w, https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/Estetica-de-lo-Salvaje-194x300.jpg 194w, https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/Estetica-de-lo-Salvaje-scaled.jpg 1657w\" sizes=\"auto, (max-width: 663px) 100vw, 663px\" \/><\/a><\/p>\n<p><strong>La est\u00e9tica de los salvaje<\/strong>, Cuernavaca, Morelos.<\/p>\n<p>La galer\u00eda NM Contempor\u00e1neo presenta la exposici\u00f3n La est\u00e9tica de lo salvaje, producida por Nora Adame y Alejandro Osorio.<\/p>\n<p>\u00c9sta obra es la consecuencia de la din\u00e1mica de exploraci\u00f3n, experimentaci\u00f3n y  desarrollo formal en donde ambos artistas seleccionan dentro de los materiales disponibles, los cuales son desechos de la industria textil, y que son asimilados como una forma de trazo pict\u00f3rico o mancha que construye una imagen donde se pueden reconocer tanto las cualidades pl\u00e1sticas del material  como su integraci\u00f3n en una escena fant\u00e1stica.<\/p>\n<div id=\"kad-wp-gallery281\" class=\"kad-wp-gallery gallery kt-gallery-column-3 init-isotope-intrinsic reinit-isotope kad-light-wp-gallery clearfix rowtight\" data-fade-in=\"1\" data-iso-selector=\".g_item\" data-iso-style=\"masonry\" data-iso-filter=\"false\"><div class=\"tcol-lg-4 tcol-md-4 tcol-sm-4 tcol-xs-6 tcol-ss-12 g_item\"><div class=\"grid_item kt_item_fade_in kad_gallery_fade_in gallery_item\"><a href=\"https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/IMG_5463-scaled.jpg\" data-rel=\"lightbox\" class=\"lightboxhover\"><div class=\"kt-intrinsic\" style=\"padding-bottom:150.27322404372%;\"><div itemprop=\"image\" itemscope itemtype=\"https:\/\/schema.org\/ImageObject\"><img loading=\"lazy\" decoding=\"async\" width=\"366\" height=\"550\" src=\"https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/IMG_5463-366x550.jpg\" srcset=\"https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/IMG_5463-366x550.jpg 366w, https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/IMG_5463-200x300.jpg 200w, https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/IMG_5463-682x1024.jpg 682w, https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/IMG_5463-732x1100.jpg 732w, https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/IMG_5463-scaled.jpg 1705w\" sizes=\"auto, (max-width: 366px) 100vw, 366px\" data-caption=\"\" class=\"light-dropshaddow\" itemprop=\"contentUrl\" alt=\"\"><meta itemprop=\"url\" content=\"https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/IMG_5463-366x550.jpg\"><meta itemprop=\"width\" content=\"366px\"><meta itemprop=\"height\" content=\"550px\"><\/div><\/div><\/a><\/div><\/div><div class=\"tcol-lg-4 tcol-md-4 tcol-sm-4 tcol-xs-6 tcol-ss-12 g_item\"><div class=\"grid_item kt_item_fade_in kad_gallery_fade_in gallery_item\"><a href=\"https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/IMG_5466-scaled.jpg\" data-rel=\"lightbox\" class=\"lightboxhover\"><div class=\"kt-intrinsic\" style=\"padding-bottom:66.666666666667%;\"><div itemprop=\"image\" itemscope itemtype=\"https:\/\/schema.org\/ImageObject\"><img loading=\"lazy\" decoding=\"async\" width=\"366\" height=\"244\" src=\"https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/IMG_5466-366x244.jpg\" srcset=\"https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/IMG_5466-366x244.jpg 366w, https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/IMG_5466-300x200.jpg 300w, https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/IMG_5466-1024x682.jpg 1024w, https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/IMG_5466-272x182.jpg 272w, https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/IMG_5466-732x488.jpg 732w\" sizes=\"auto, (max-width: 366px) 100vw, 366px\" data-caption=\"\" class=\"light-dropshaddow\" itemprop=\"contentUrl\" alt=\"\"><meta itemprop=\"url\" content=\"https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/IMG_5466-366x244.jpg\"><meta itemprop=\"width\" content=\"366px\"><meta itemprop=\"height\" content=\"244px\"><\/div><\/div><\/a><\/div><\/div><div class=\"tcol-lg-4 tcol-md-4 tcol-sm-4 tcol-xs-6 tcol-ss-12 g_item\"><div class=\"grid_item kt_item_fade_in kad_gallery_fade_in gallery_item\"><a href=\"https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/IMG_5465-scaled.jpg\" data-rel=\"lightbox\" class=\"lightboxhover\"><div class=\"kt-intrinsic\" style=\"padding-bottom:66.666666666667%;\"><div itemprop=\"image\" itemscope itemtype=\"https:\/\/schema.org\/ImageObject\"><img loading=\"lazy\" decoding=\"async\" width=\"366\" height=\"244\" src=\"https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/IMG_5465-366x244.jpg\" srcset=\"https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/IMG_5465-366x244.jpg 366w, https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/IMG_5465-300x200.jpg 300w, https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/IMG_5465-1024x682.jpg 1024w, https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/IMG_5465-272x182.jpg 272w, https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/IMG_5465-732x488.jpg 732w\" sizes=\"auto, (max-width: 366px) 100vw, 366px\" data-caption=\"\" class=\"light-dropshaddow\" itemprop=\"contentUrl\" alt=\"\"><meta itemprop=\"url\" content=\"https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/IMG_5465-366x244.jpg\"><meta itemprop=\"width\" content=\"366px\"><meta itemprop=\"height\" content=\"244px\"><\/div><\/div><\/a><\/div><\/div><div class=\"tcol-lg-4 tcol-md-4 tcol-sm-4 tcol-xs-6 tcol-ss-12 g_item\"><div class=\"grid_item kt_item_fade_in kad_gallery_fade_in gallery_item\"><a href=\"https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/IMG_5457-scaled.jpg\" data-rel=\"lightbox\" class=\"lightboxhover\"><div class=\"kt-intrinsic\" style=\"padding-bottom:66.666666666667%;\"><div itemprop=\"image\" itemscope itemtype=\"https:\/\/schema.org\/ImageObject\"><img loading=\"lazy\" decoding=\"async\" width=\"366\" height=\"244\" src=\"https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/IMG_5457-366x244.jpg\" srcset=\"https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/IMG_5457-366x244.jpg 366w, https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/IMG_5457-300x200.jpg 300w, https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/IMG_5457-1024x682.jpg 1024w, https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/IMG_5457-272x182.jpg 272w, https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/IMG_5457-732x488.jpg 732w\" sizes=\"auto, (max-width: 366px) 100vw, 366px\" data-caption=\"\" class=\"light-dropshaddow\" itemprop=\"contentUrl\" alt=\"\"><meta itemprop=\"url\" content=\"https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/IMG_5457-366x244.jpg\"><meta itemprop=\"width\" content=\"366px\"><meta itemprop=\"height\" content=\"244px\"><\/div><\/div><\/a><\/div><\/div><div class=\"tcol-lg-4 tcol-md-4 tcol-sm-4 tcol-xs-6 tcol-ss-12 g_item\"><div class=\"grid_item kt_item_fade_in kad_gallery_fade_in gallery_item\"><a href=\"https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/IMG_5459-scaled.jpg\" data-rel=\"lightbox\" class=\"lightboxhover\"><div class=\"kt-intrinsic\" style=\"padding-bottom:66.666666666667%;\"><div itemprop=\"image\" itemscope itemtype=\"https:\/\/schema.org\/ImageObject\"><img loading=\"lazy\" decoding=\"async\" width=\"366\" height=\"244\" src=\"https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/IMG_5459-366x244.jpg\" srcset=\"https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/IMG_5459-366x244.jpg 366w, https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/IMG_5459-300x200.jpg 300w, https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/IMG_5459-1024x682.jpg 1024w, https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/IMG_5459-272x182.jpg 272w, https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/IMG_5459-732x488.jpg 732w\" sizes=\"auto, (max-width: 366px) 100vw, 366px\" data-caption=\"\" class=\"light-dropshaddow\" itemprop=\"contentUrl\" alt=\"\"><meta itemprop=\"url\" content=\"https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/IMG_5459-366x244.jpg\"><meta itemprop=\"width\" content=\"366px\"><meta itemprop=\"height\" content=\"244px\"><\/div><\/div><\/a><\/div><\/div><div class=\"tcol-lg-4 tcol-md-4 tcol-sm-4 tcol-xs-6 tcol-ss-12 g_item\"><div class=\"grid_item kt_item_fade_in kad_gallery_fade_in gallery_item\"><a href=\"https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/IMG_5456-scaled.jpg\" data-rel=\"lightbox\" class=\"lightboxhover\"><div class=\"kt-intrinsic\" style=\"padding-bottom:66.666666666667%;\"><div itemprop=\"image\" itemscope itemtype=\"https:\/\/schema.org\/ImageObject\"><img loading=\"lazy\" decoding=\"async\" width=\"366\" height=\"244\" src=\"https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/IMG_5456-366x244.jpg\" srcset=\"https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/IMG_5456-366x244.jpg 366w, https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/IMG_5456-300x200.jpg 300w, https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/IMG_5456-1024x682.jpg 1024w, https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/IMG_5456-272x182.jpg 272w, https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/IMG_5456-732x488.jpg 732w\" sizes=\"auto, (max-width: 366px) 100vw, 366px\" data-caption=\"\" class=\"light-dropshaddow\" itemprop=\"contentUrl\" alt=\"\"><meta itemprop=\"url\" content=\"https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/IMG_5456-366x244.jpg\"><meta itemprop=\"width\" content=\"366px\"><meta itemprop=\"height\" content=\"244px\"><\/div><\/div><\/a><\/div><\/div><div class=\"tcol-lg-4 tcol-md-4 tcol-sm-4 tcol-xs-6 tcol-ss-12 g_item\"><div class=\"grid_item kt_item_fade_in kad_gallery_fade_in gallery_item\"><a href=\"https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/IMG_5474-scaled.jpg\" data-rel=\"lightbox\" class=\"lightboxhover\"><div class=\"kt-intrinsic\" style=\"padding-bottom:150.27322404372%;\"><div itemprop=\"image\" itemscope itemtype=\"https:\/\/schema.org\/ImageObject\"><img loading=\"lazy\" decoding=\"async\" width=\"366\" height=\"550\" src=\"https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/IMG_5474-366x550.jpg\" srcset=\"https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/IMG_5474-366x550.jpg 366w, https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/IMG_5474-200x300.jpg 200w, https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/IMG_5474-682x1024.jpg 682w, https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/IMG_5474-732x1100.jpg 732w, https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/IMG_5474-scaled.jpg 1705w\" sizes=\"auto, (max-width: 366px) 100vw, 366px\" data-caption=\"\" class=\"light-dropshaddow\" itemprop=\"contentUrl\" alt=\"\"><meta itemprop=\"url\" content=\"https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/IMG_5474-366x550.jpg\"><meta itemprop=\"width\" content=\"366px\"><meta itemprop=\"height\" content=\"550px\"><\/div><\/div><\/a><\/div><\/div><div class=\"tcol-lg-4 tcol-md-4 tcol-sm-4 tcol-xs-6 tcol-ss-12 g_item\"><div class=\"grid_item kt_item_fade_in kad_gallery_fade_in gallery_item\"><a href=\"https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/IMG_5467-scaled.jpg\" data-rel=\"lightbox\" class=\"lightboxhover\"><div class=\"kt-intrinsic\" style=\"padding-bottom:66.666666666667%;\"><div itemprop=\"image\" itemscope itemtype=\"https:\/\/schema.org\/ImageObject\"><img loading=\"lazy\" decoding=\"async\" width=\"366\" height=\"244\" src=\"https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/IMG_5467-366x244.jpg\" srcset=\"https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/IMG_5467-366x244.jpg 366w, https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/IMG_5467-300x200.jpg 300w, https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/IMG_5467-1024x682.jpg 1024w, https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/IMG_5467-272x182.jpg 272w, https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/IMG_5467-732x488.jpg 732w\" sizes=\"auto, (max-width: 366px) 100vw, 366px\" data-caption=\"\" class=\"light-dropshaddow\" itemprop=\"contentUrl\" alt=\"\"><meta itemprop=\"url\" content=\"https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/IMG_5467-366x244.jpg\"><meta itemprop=\"width\" content=\"366px\"><meta itemprop=\"height\" content=\"244px\"><\/div><\/div><\/a><\/div><\/div><div class=\"tcol-lg-4 tcol-md-4 tcol-sm-4 tcol-xs-6 tcol-ss-12 g_item\"><div class=\"grid_item kt_item_fade_in kad_gallery_fade_in gallery_item\"><a href=\"https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/IMG_5471-scaled.jpg\" data-rel=\"lightbox\" class=\"lightboxhover\"><div class=\"kt-intrinsic\" style=\"padding-bottom:66.666666666667%;\"><div itemprop=\"image\" itemscope itemtype=\"https:\/\/schema.org\/ImageObject\"><img loading=\"lazy\" decoding=\"async\" width=\"366\" height=\"244\" src=\"https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/IMG_5471-366x244.jpg\" srcset=\"https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/IMG_5471-366x244.jpg 366w, https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/IMG_5471-300x200.jpg 300w, https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/IMG_5471-1024x682.jpg 1024w, https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/IMG_5471-272x182.jpg 272w, https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/IMG_5471-732x488.jpg 732w\" sizes=\"auto, (max-width: 366px) 100vw, 366px\" data-caption=\"\" class=\"light-dropshaddow\" itemprop=\"contentUrl\" alt=\"\"><meta itemprop=\"url\" content=\"https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/IMG_5471-366x244.jpg\"><meta itemprop=\"width\" content=\"366px\"><meta itemprop=\"height\" content=\"244px\"><\/div><\/div><\/a><\/div><\/div><div class=\"tcol-lg-4 tcol-md-4 tcol-sm-4 tcol-xs-6 tcol-ss-12 g_item\"><div class=\"grid_item kt_item_fade_in kad_gallery_fade_in gallery_item\"><a href=\"https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/IMG_5458-scaled.jpg\" data-rel=\"lightbox\" class=\"lightboxhover\"><div class=\"kt-intrinsic\" style=\"padding-bottom:66.666666666667%;\"><div itemprop=\"image\" itemscope itemtype=\"https:\/\/schema.org\/ImageObject\"><img loading=\"lazy\" decoding=\"async\" width=\"366\" height=\"244\" src=\"https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/IMG_5458-366x244.jpg\" srcset=\"https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/IMG_5458-366x244.jpg 366w, https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/IMG_5458-300x200.jpg 300w, https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/IMG_5458-1024x682.jpg 1024w, https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/IMG_5458-272x182.jpg 272w, https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/IMG_5458-732x488.jpg 732w\" sizes=\"auto, (max-width: 366px) 100vw, 366px\" data-caption=\"\" class=\"light-dropshaddow\" itemprop=\"contentUrl\" alt=\"\"><meta itemprop=\"url\" content=\"https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/IMG_5458-366x244.jpg\"><meta itemprop=\"width\" content=\"366px\"><meta itemprop=\"height\" content=\"244px\"><\/div><\/div><\/a><\/div><\/div><div class=\"tcol-lg-4 tcol-md-4 tcol-sm-4 tcol-xs-6 tcol-ss-12 g_item\"><div class=\"grid_item kt_item_fade_in kad_gallery_fade_in gallery_item\"><a href=\"https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/IMG_5470-scaled.jpg\" data-rel=\"lightbox\" class=\"lightboxhover\"><div class=\"kt-intrinsic\" style=\"padding-bottom:66.666666666667%;\"><div itemprop=\"image\" itemscope itemtype=\"https:\/\/schema.org\/ImageObject\"><img loading=\"lazy\" decoding=\"async\" width=\"366\" height=\"244\" src=\"https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/IMG_5470-366x244.jpg\" srcset=\"https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/IMG_5470-366x244.jpg 366w, https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/IMG_5470-300x200.jpg 300w, https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/IMG_5470-1024x682.jpg 1024w, https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/IMG_5470-272x182.jpg 272w, https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/IMG_5470-732x488.jpg 732w\" sizes=\"auto, (max-width: 366px) 100vw, 366px\" data-caption=\"\" class=\"light-dropshaddow\" itemprop=\"contentUrl\" alt=\"\"><meta itemprop=\"url\" content=\"https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/IMG_5470-366x244.jpg\"><meta itemprop=\"width\" content=\"366px\"><meta itemprop=\"height\" content=\"244px\"><\/div><\/div><\/a><\/div><\/div><div class=\"tcol-lg-4 tcol-md-4 tcol-sm-4 tcol-xs-6 tcol-ss-12 g_item\"><div class=\"grid_item kt_item_fade_in kad_gallery_fade_in gallery_item\"><a href=\"https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/IMG_5460-scaled.jpg\" data-rel=\"lightbox\" class=\"lightboxhover\"><div class=\"kt-intrinsic\" style=\"padding-bottom:66.666666666667%;\"><div itemprop=\"image\" itemscope itemtype=\"https:\/\/schema.org\/ImageObject\"><img loading=\"lazy\" decoding=\"async\" width=\"366\" height=\"244\" src=\"https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/IMG_5460-366x244.jpg\" srcset=\"https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/IMG_5460-366x244.jpg 366w, https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/IMG_5460-300x200.jpg 300w, https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/IMG_5460-1024x682.jpg 1024w, https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/IMG_5460-272x182.jpg 272w, https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/IMG_5460-732x488.jpg 732w\" sizes=\"auto, (max-width: 366px) 100vw, 366px\" data-caption=\"\" class=\"light-dropshaddow\" itemprop=\"contentUrl\" alt=\"\"><meta itemprop=\"url\" content=\"https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/IMG_5460-366x244.jpg\"><meta itemprop=\"width\" content=\"366px\"><meta itemprop=\"height\" content=\"244px\"><\/div><\/div><\/a><\/div><\/div><div class=\"tcol-lg-4 tcol-md-4 tcol-sm-4 tcol-xs-6 tcol-ss-12 g_item\"><div class=\"grid_item kt_item_fade_in kad_gallery_fade_in gallery_item\"><a href=\"https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/IMG_5461-scaled.jpg\" data-rel=\"lightbox\" class=\"lightboxhover\"><div class=\"kt-intrinsic\" style=\"padding-bottom:66.666666666667%;\"><div itemprop=\"image\" itemscope itemtype=\"https:\/\/schema.org\/ImageObject\"><img loading=\"lazy\" decoding=\"async\" width=\"366\" height=\"244\" src=\"https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/IMG_5461-366x244.jpg\" srcset=\"https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/IMG_5461-366x244.jpg 366w, https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/IMG_5461-300x200.jpg 300w, https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/IMG_5461-1024x682.jpg 1024w, https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/IMG_5461-272x182.jpg 272w, https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/IMG_5461-732x488.jpg 732w\" sizes=\"auto, (max-width: 366px) 100vw, 366px\" data-caption=\"\" class=\"light-dropshaddow\" itemprop=\"contentUrl\" alt=\"\"><meta itemprop=\"url\" content=\"https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/IMG_5461-366x244.jpg\"><meta itemprop=\"width\" content=\"366px\"><meta itemprop=\"height\" content=\"244px\"><\/div><\/div><\/a><\/div><\/div><div class=\"tcol-lg-4 tcol-md-4 tcol-sm-4 tcol-xs-6 tcol-ss-12 g_item\"><div class=\"grid_item kt_item_fade_in kad_gallery_fade_in gallery_item\"><a href=\"https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/IMG_5462-scaled.jpg\" data-rel=\"lightbox\" class=\"lightboxhover\"><div class=\"kt-intrinsic\" style=\"padding-bottom:150.27322404372%;\"><div itemprop=\"image\" itemscope itemtype=\"https:\/\/schema.org\/ImageObject\"><img loading=\"lazy\" decoding=\"async\" width=\"366\" height=\"550\" src=\"https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/IMG_5462-366x550.jpg\" srcset=\"https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/IMG_5462-366x550.jpg 366w, https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/IMG_5462-200x300.jpg 200w, https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/IMG_5462-682x1024.jpg 682w, https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/IMG_5462-732x1100.jpg 732w, https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/IMG_5462-scaled.jpg 1705w\" sizes=\"auto, (max-width: 366px) 100vw, 366px\" data-caption=\"\" class=\"light-dropshaddow\" itemprop=\"contentUrl\" alt=\"\"><meta itemprop=\"url\" content=\"https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/IMG_5462-366x550.jpg\"><meta itemprop=\"width\" content=\"366px\"><meta itemprop=\"height\" content=\"550px\"><\/div><\/div><\/a><\/div><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>La est\u00e9tica de los salvaje, Cuernavaca, Morelos. La galer\u00eda NM Contempor\u00e1neo presenta la exposici\u00f3n La est\u00e9tica de lo salvaje, producida por Nora Adame y Alejandro Osorio. \u00c9sta obra es la consecuencia de la din\u00e1mica de exploraci\u00f3n, experimentaci\u00f3n y desarrollo formal &hellip; <a class=\"kt-excerpt-readmore\" href=\"https:\/\/nmcontemporaneo.com\/en\/la-estetica-de-los-salvaje-2014\/\" aria-label=\"\">Read More<\/a><\/p>\n","protected":false},"author":25,"featured_media":6993,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"kt_blocks_editor_width":"","footnotes":""},"categories":[51],"tags":[277,102,275,103,276],"class_list":["post-6991","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-exhibitions","tag-alejandro-osorio","tag-cuernavaca","tag-la-estetica-de-lo-salvaje","tag-morelos","tag-nora-adame"],"_links":{"self":[{"href":"https:\/\/nmcontemporaneo.com\/en\/wp-json\/wp\/v2\/posts\/6991","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nmcontemporaneo.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/nmcontemporaneo.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/nmcontemporaneo.com\/en\/wp-json\/wp\/v2\/users\/25"}],"replies":[{"embeddable":true,"href":"https:\/\/nmcontemporaneo.com\/en\/wp-json\/wp\/v2\/comments?post=6991"}],"version-history":[{"count":1,"href":"https:\/\/nmcontemporaneo.com\/en\/wp-json\/wp\/v2\/posts\/6991\/revisions"}],"predecessor-version":[{"id":14046,"href":"https:\/\/nmcontemporaneo.com\/en\/wp-json\/wp\/v2\/posts\/6991\/revisions\/14046"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/nmcontemporaneo.com\/en\/wp-json\/wp\/v2\/media\/6993"}],"wp:attachment":[{"href":"https:\/\/nmcontemporaneo.com\/en\/wp-json\/wp\/v2\/media?parent=6991"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/nmcontemporaneo.com\/en\/wp-json\/wp\/v2\/categories?post=6991"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/nmcontemporaneo.com\/en\/wp-json\/wp\/v2\/tags?post=6991"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}