{"id":7054,"date":"2014-03-15T21:41:49","date_gmt":"2014-03-16T03:41:49","guid":{"rendered":"http:\/\/nmcontemporaneo.com\/beta\/?p=7054"},"modified":"2025-06-20T01:02:29","modified_gmt":"2025-06-20T07:02:29","slug":"de-la-forma-a-la-funcion-2014","status":"publish","type":"post","link":"https:\/\/nmcontemporaneo.com\/en\/de-la-forma-a-la-funcion-2014\/","title":{"rendered":""},"content":{"rendered":"<p><a href=\"http:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/Forma-Func-NM-digital721.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-7116\" src=\"http:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/Forma-Func-NM-digital721.jpg\" alt=\"Forma-Func-NM-(digital72)\" width=\"539\" height=\"852\" srcset=\"https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/Forma-Func-NM-digital721.jpg 539w, https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/Forma-Func-NM-digital721-190x300.jpg 190w\" sizes=\"auto, (max-width: 539px) 100vw, 539px\" \/><\/a><\/p>\n<p><strong>De la forma a la funci\u00f3n<\/strong>. Cuernavaca, Morelos.<\/p>\n<p style=\"text-align: justify;\">La galer\u00eda NM Contempor\u00e1neo presenta la exposici\u00f3n De la forma a la funci\u00f3n, producida por el artista multidisciplinario y fil\u00f3sofo mexicano Nacho Rodriguez Bach (Ciudad de M\u00e9xico, 1966). Especializado en medios electr\u00f3nicos, Rodr\u00edguez Bach cuenta con una s\u00f3lida trayectoria a nivel internacional. Creador de propuestas sonoras que bajo el t\u00e9rmino de m\u00fasica visual se circunscribe en la multidisciplina conceptual y las instalaciones en sitio espec\u00edfico.<\/p>\n<div id=\"kad-wp-gallery809\" class=\"kad-wp-gallery gallery kt-gallery-column-3 init-isotope-intrinsic reinit-isotope kad-light-wp-gallery clearfix rowtight\" data-fade-in=\"1\" data-iso-selector=\".g_item\" data-iso-style=\"masonry\" data-iso-filter=\"false\"><div class=\"tcol-lg-4 tcol-md-4 tcol-sm-4 tcol-xs-6 tcol-ss-12 g_item\"><div class=\"grid_item kt_item_fade_in kad_gallery_fade_in gallery_item\"><a href=\"https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/1-expo1.jpg\" data-rel=\"lightbox\" class=\"lightboxhover\"><div class=\"kt-intrinsic\" style=\"padding-bottom:56.284153005464%;\"><div itemprop=\"image\" itemscope itemtype=\"https:\/\/schema.org\/ImageObject\"><img loading=\"lazy\" decoding=\"async\" width=\"366\" height=\"206\" src=\"https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/1-expo1-366x206.jpg\" srcset=\"https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/1-expo1-366x206.jpg 366w, https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/1-expo1-300x169.jpg 300w, https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/1-expo1.jpg 700w\" sizes=\"auto, (max-width: 366px) 100vw, 366px\" data-caption=\"\" class=\"light-dropshaddow\" itemprop=\"contentUrl\" alt=\"\"><meta itemprop=\"url\" content=\"https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/1-expo1-366x206.jpg\"><meta itemprop=\"width\" content=\"366px\"><meta itemprop=\"height\" content=\"206px\"><\/div><\/div><\/a><\/div><\/div><div class=\"tcol-lg-4 tcol-md-4 tcol-sm-4 tcol-xs-6 tcol-ss-12 g_item\"><div class=\"grid_item kt_item_fade_in kad_gallery_fade_in gallery_item\"><a href=\"https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/2-expo1.jpg\" data-rel=\"lightbox\" class=\"lightboxhover\"><div class=\"kt-intrinsic\" style=\"padding-bottom:56.284153005464%;\"><div itemprop=\"image\" itemscope itemtype=\"https:\/\/schema.org\/ImageObject\"><img loading=\"lazy\" decoding=\"async\" width=\"366\" height=\"206\" src=\"https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/2-expo1-366x206.jpg\" srcset=\"https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/2-expo1-366x206.jpg 366w, https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/2-expo1-300x169.jpg 300w, https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/2-expo1.jpg 700w\" sizes=\"auto, (max-width: 366px) 100vw, 366px\" data-caption=\"\" class=\"light-dropshaddow\" itemprop=\"contentUrl\" alt=\"\"><meta itemprop=\"url\" content=\"https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/2-expo1-366x206.jpg\"><meta itemprop=\"width\" content=\"366px\"><meta itemprop=\"height\" content=\"206px\"><\/div><\/div><\/a><\/div><\/div><div class=\"tcol-lg-4 tcol-md-4 tcol-sm-4 tcol-xs-6 tcol-ss-12 g_item\"><div class=\"grid_item kt_item_fade_in kad_gallery_fade_in gallery_item\"><a href=\"https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/3-expo.jpg\" data-rel=\"lightbox\" class=\"lightboxhover\"><div class=\"kt-intrinsic\" style=\"padding-bottom:56.284153005464%;\"><div itemprop=\"image\" itemscope itemtype=\"https:\/\/schema.org\/ImageObject\"><img loading=\"lazy\" decoding=\"async\" width=\"366\" height=\"206\" src=\"https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/3-expo-366x206.jpg\" srcset=\"https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/3-expo-366x206.jpg 366w, https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/3-expo-300x169.jpg 300w, https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/3-expo.jpg 700w\" sizes=\"auto, (max-width: 366px) 100vw, 366px\" data-caption=\"\" class=\"light-dropshaddow\" itemprop=\"contentUrl\" alt=\"\"><meta itemprop=\"url\" content=\"https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/3-expo-366x206.jpg\"><meta itemprop=\"width\" content=\"366px\"><meta itemprop=\"height\" content=\"206px\"><\/div><\/div><\/a><\/div><\/div><div class=\"tcol-lg-4 tcol-md-4 tcol-sm-4 tcol-xs-6 tcol-ss-12 g_item\"><div class=\"grid_item kt_item_fade_in kad_gallery_fade_in gallery_item\"><a href=\"https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/8-expo1.jpg\" data-rel=\"lightbox\" class=\"lightboxhover\"><div class=\"kt-intrinsic\" style=\"padding-bottom:56.284153005464%;\"><div itemprop=\"image\" itemscope itemtype=\"https:\/\/schema.org\/ImageObject\"><img loading=\"lazy\" decoding=\"async\" width=\"366\" height=\"206\" src=\"https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/8-expo1-366x206.jpg\" srcset=\"https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/8-expo1-366x206.jpg 366w, https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/8-expo1-300x169.jpg 300w, https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/8-expo1.jpg 700w\" sizes=\"auto, (max-width: 366px) 100vw, 366px\" data-caption=\"\" class=\"light-dropshaddow\" itemprop=\"contentUrl\" alt=\"\"><meta itemprop=\"url\" content=\"https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/8-expo1-366x206.jpg\"><meta itemprop=\"width\" content=\"366px\"><meta itemprop=\"height\" content=\"206px\"><\/div><\/div><\/a><\/div><\/div><div class=\"tcol-lg-4 tcol-md-4 tcol-sm-4 tcol-xs-6 tcol-ss-12 g_item\"><div class=\"grid_item kt_item_fade_in kad_gallery_fade_in gallery_item\"><a href=\"https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/11expo1.jpg\" data-rel=\"lightbox\" class=\"lightboxhover\"><div class=\"kt-intrinsic\" style=\"padding-bottom:56.284153005464%;\"><div itemprop=\"image\" itemscope itemtype=\"https:\/\/schema.org\/ImageObject\"><img loading=\"lazy\" decoding=\"async\" width=\"366\" height=\"206\" src=\"https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/11expo1-366x206.jpg\" srcset=\"https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/11expo1-366x206.jpg 366w, https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/11expo1-300x169.jpg 300w, https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/11expo1.jpg 700w\" sizes=\"auto, (max-width: 366px) 100vw, 366px\" data-caption=\"\" class=\"light-dropshaddow\" itemprop=\"contentUrl\" alt=\"\"><meta itemprop=\"url\" content=\"https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/11expo1-366x206.jpg\"><meta itemprop=\"width\" content=\"366px\"><meta itemprop=\"height\" content=\"206px\"><\/div><\/div><\/a><\/div><\/div><div class=\"tcol-lg-4 tcol-md-4 tcol-sm-4 tcol-xs-6 tcol-ss-12 g_item\"><div class=\"grid_item kt_item_fade_in kad_gallery_fade_in gallery_item\"><a href=\"https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/12-expo1.jpg\" data-rel=\"lightbox\" class=\"lightboxhover\"><div class=\"kt-intrinsic\" style=\"padding-bottom:56.284153005464%;\"><div itemprop=\"image\" itemscope itemtype=\"https:\/\/schema.org\/ImageObject\"><img loading=\"lazy\" decoding=\"async\" width=\"366\" height=\"206\" src=\"https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/12-expo1-366x206.jpg\" srcset=\"https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/12-expo1-366x206.jpg 366w, https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/12-expo1-300x169.jpg 300w, https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/12-expo1.jpg 700w\" sizes=\"auto, (max-width: 366px) 100vw, 366px\" data-caption=\"\" class=\"light-dropshaddow\" itemprop=\"contentUrl\" alt=\"\"><meta itemprop=\"url\" content=\"https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/12-expo1-366x206.jpg\"><meta itemprop=\"width\" content=\"366px\"><meta itemprop=\"height\" content=\"206px\"><\/div><\/div><\/a><\/div><\/div><div class=\"tcol-lg-4 tcol-md-4 tcol-sm-4 tcol-xs-6 tcol-ss-12 g_item\"><div class=\"grid_item kt_item_fade_in kad_gallery_fade_in gallery_item\"><a href=\"https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/IMG_57571-scaled.jpg\" data-rel=\"lightbox\" class=\"lightboxhover\"><div class=\"kt-intrinsic\" style=\"padding-bottom:66.666666666667%;\"><div itemprop=\"image\" itemscope itemtype=\"https:\/\/schema.org\/ImageObject\"><img loading=\"lazy\" decoding=\"async\" width=\"366\" height=\"244\" src=\"https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/IMG_57571-366x244.jpg\" srcset=\"https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/IMG_57571-366x244.jpg 366w, https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/IMG_57571-300x200.jpg 300w, https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/IMG_57571-1024x682.jpg 1024w, https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/IMG_57571-272x182.jpg 272w, https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/IMG_57571-732x488.jpg 732w\" sizes=\"auto, (max-width: 366px) 100vw, 366px\" data-caption=\"\" class=\"light-dropshaddow\" itemprop=\"contentUrl\" alt=\"\"><meta itemprop=\"url\" content=\"https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/IMG_57571-366x244.jpg\"><meta itemprop=\"width\" content=\"366px\"><meta itemprop=\"height\" content=\"244px\"><\/div><\/div><\/a><\/div><\/div><div class=\"tcol-lg-4 tcol-md-4 tcol-sm-4 tcol-xs-6 tcol-ss-12 g_item\"><div class=\"grid_item kt_item_fade_in kad_gallery_fade_in gallery_item\"><a href=\"https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/IMG_57561-scaled.jpg\" data-rel=\"lightbox\" class=\"lightboxhover\"><div class=\"kt-intrinsic\" style=\"padding-bottom:66.666666666667%;\"><div itemprop=\"image\" itemscope itemtype=\"https:\/\/schema.org\/ImageObject\"><img loading=\"lazy\" decoding=\"async\" width=\"366\" height=\"244\" src=\"https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/IMG_57561-366x244.jpg\" srcset=\"https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/IMG_57561-366x244.jpg 366w, https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/IMG_57561-300x200.jpg 300w, https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/IMG_57561-1024x682.jpg 1024w, https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/IMG_57561-272x182.jpg 272w, https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/IMG_57561-732x488.jpg 732w\" sizes=\"auto, (max-width: 366px) 100vw, 366px\" data-caption=\"\" class=\"light-dropshaddow\" itemprop=\"contentUrl\" alt=\"\"><meta itemprop=\"url\" content=\"https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/IMG_57561-366x244.jpg\"><meta itemprop=\"width\" content=\"366px\"><meta itemprop=\"height\" content=\"244px\"><\/div><\/div><\/a><\/div><\/div><div class=\"tcol-lg-4 tcol-md-4 tcol-sm-4 tcol-xs-6 tcol-ss-12 g_item\"><div class=\"grid_item kt_item_fade_in kad_gallery_fade_in gallery_item\"><a href=\"https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/IMG_57551-scaled.jpg\" data-rel=\"lightbox\" class=\"lightboxhover\"><div class=\"kt-intrinsic\" style=\"padding-bottom:66.666666666667%;\"><div itemprop=\"image\" itemscope itemtype=\"https:\/\/schema.org\/ImageObject\"><img loading=\"lazy\" decoding=\"async\" width=\"366\" height=\"244\" src=\"https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/IMG_57551-366x244.jpg\" srcset=\"https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/IMG_57551-366x244.jpg 366w, https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/IMG_57551-300x200.jpg 300w, https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/IMG_57551-1024x682.jpg 1024w, https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/IMG_57551-272x182.jpg 272w, https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/IMG_57551-732x488.jpg 732w\" sizes=\"auto, (max-width: 366px) 100vw, 366px\" data-caption=\"\" class=\"light-dropshaddow\" itemprop=\"contentUrl\" alt=\"\"><meta itemprop=\"url\" content=\"https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/IMG_57551-366x244.jpg\"><meta itemprop=\"width\" content=\"366px\"><meta itemprop=\"height\" content=\"244px\"><\/div><\/div><\/a><\/div><\/div><div class=\"tcol-lg-4 tcol-md-4 tcol-sm-4 tcol-xs-6 tcol-ss-12 g_item\"><div class=\"grid_item kt_item_fade_in kad_gallery_fade_in gallery_item\"><a href=\"https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/IMG_57541-scaled.jpg\" data-rel=\"lightbox\" class=\"lightboxhover\"><div class=\"kt-intrinsic\" style=\"padding-bottom:66.666666666667%;\"><div itemprop=\"image\" itemscope itemtype=\"https:\/\/schema.org\/ImageObject\"><img loading=\"lazy\" decoding=\"async\" width=\"366\" height=\"244\" src=\"https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/IMG_57541-366x244.jpg\" srcset=\"https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/IMG_57541-366x244.jpg 366w, https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/IMG_57541-300x200.jpg 300w, https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/IMG_57541-1024x682.jpg 1024w, https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/IMG_57541-272x182.jpg 272w, https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/IMG_57541-732x488.jpg 732w\" sizes=\"auto, (max-width: 366px) 100vw, 366px\" data-caption=\"\" class=\"light-dropshaddow\" itemprop=\"contentUrl\" alt=\"\"><meta itemprop=\"url\" content=\"https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/IMG_57541-366x244.jpg\"><meta itemprop=\"width\" content=\"366px\"><meta itemprop=\"height\" content=\"244px\"><\/div><\/div><\/a><\/div><\/div><div class=\"tcol-lg-4 tcol-md-4 tcol-sm-4 tcol-xs-6 tcol-ss-12 g_item\"><div class=\"grid_item kt_item_fade_in kad_gallery_fade_in gallery_item\"><a href=\"https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/13-expo1.jpg\" data-rel=\"lightbox\" class=\"lightboxhover\"><div class=\"kt-intrinsic\" style=\"padding-bottom:56.284153005464%;\"><div itemprop=\"image\" itemscope itemtype=\"https:\/\/schema.org\/ImageObject\"><img loading=\"lazy\" decoding=\"async\" width=\"366\" height=\"206\" src=\"https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/13-expo1-366x206.jpg\" srcset=\"https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/13-expo1-366x206.jpg 366w, https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/13-expo1-300x169.jpg 300w, https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/13-expo1.jpg 700w\" sizes=\"auto, (max-width: 366px) 100vw, 366px\" data-caption=\"\" class=\"light-dropshaddow\" itemprop=\"contentUrl\" alt=\"\"><meta itemprop=\"url\" content=\"https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/13-expo1-366x206.jpg\"><meta itemprop=\"width\" content=\"366px\"><meta itemprop=\"height\" content=\"206px\"><\/div><\/div><\/a><\/div><\/div><div class=\"tcol-lg-4 tcol-md-4 tcol-sm-4 tcol-xs-6 tcol-ss-12 g_item\"><div class=\"grid_item kt_item_fade_in kad_gallery_fade_in gallery_item\"><a href=\"https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/IMG_57581-scaled.jpg\" data-rel=\"lightbox\" class=\"lightboxhover\"><div class=\"kt-intrinsic\" style=\"padding-bottom:66.666666666667%;\"><div itemprop=\"image\" itemscope itemtype=\"https:\/\/schema.org\/ImageObject\"><img loading=\"lazy\" decoding=\"async\" width=\"366\" height=\"244\" src=\"https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/IMG_57581-366x244.jpg\" srcset=\"https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/IMG_57581-366x244.jpg 366w, https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/IMG_57581-300x200.jpg 300w, https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/IMG_57581-1024x682.jpg 1024w, https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/IMG_57581-272x182.jpg 272w, https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/IMG_57581-732x488.jpg 732w\" sizes=\"auto, (max-width: 366px) 100vw, 366px\" data-caption=\"\" class=\"light-dropshaddow\" itemprop=\"contentUrl\" alt=\"\"><meta itemprop=\"url\" content=\"https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/IMG_57581-366x244.jpg\"><meta itemprop=\"width\" content=\"366px\"><meta itemprop=\"height\" content=\"244px\"><\/div><\/div><\/a><\/div><\/div><div class=\"tcol-lg-4 tcol-md-4 tcol-sm-4 tcol-xs-6 tcol-ss-12 g_item\"><div class=\"grid_item kt_item_fade_in kad_gallery_fade_in gallery_item\"><a href=\"https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/IMG_57611-scaled.jpg\" data-rel=\"lightbox\" class=\"lightboxhover\"><div class=\"kt-intrinsic\" style=\"padding-bottom:150.27322404372%;\"><div itemprop=\"image\" itemscope itemtype=\"https:\/\/schema.org\/ImageObject\"><img loading=\"lazy\" decoding=\"async\" width=\"366\" height=\"550\" src=\"https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/IMG_57611-366x550.jpg\" srcset=\"https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/IMG_57611-366x550.jpg 366w, https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/IMG_57611-200x300.jpg 200w, https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/IMG_57611-682x1024.jpg 682w, https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/IMG_57611-732x1100.jpg 732w, https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/IMG_57611-scaled.jpg 1705w\" sizes=\"auto, (max-width: 366px) 100vw, 366px\" data-caption=\"\" class=\"light-dropshaddow\" itemprop=\"contentUrl\" alt=\"\"><meta itemprop=\"url\" content=\"https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/IMG_57611-366x550.jpg\"><meta itemprop=\"width\" content=\"366px\"><meta itemprop=\"height\" content=\"550px\"><\/div><\/div><\/a><\/div><\/div><div class=\"tcol-lg-4 tcol-md-4 tcol-sm-4 tcol-xs-6 tcol-ss-12 g_item\"><div class=\"grid_item kt_item_fade_in kad_gallery_fade_in gallery_item\"><a href=\"https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/IMG_57621-scaled.jpg\" data-rel=\"lightbox\" class=\"lightboxhover\"><div class=\"kt-intrinsic\" style=\"padding-bottom:66.666666666667%;\"><div itemprop=\"image\" itemscope itemtype=\"https:\/\/schema.org\/ImageObject\"><img loading=\"lazy\" decoding=\"async\" width=\"366\" height=\"244\" src=\"https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/IMG_57621-366x244.jpg\" srcset=\"https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/IMG_57621-366x244.jpg 366w, https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/IMG_57621-300x200.jpg 300w, https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/IMG_57621-1024x682.jpg 1024w, https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/IMG_57621-272x182.jpg 272w, https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/IMG_57621-732x488.jpg 732w\" sizes=\"auto, (max-width: 366px) 100vw, 366px\" data-caption=\"\" class=\"light-dropshaddow\" itemprop=\"contentUrl\" alt=\"\"><meta itemprop=\"url\" content=\"https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/IMG_57621-366x244.jpg\"><meta itemprop=\"width\" content=\"366px\"><meta itemprop=\"height\" content=\"244px\"><\/div><\/div><\/a><\/div><\/div><div class=\"tcol-lg-4 tcol-md-4 tcol-sm-4 tcol-xs-6 tcol-ss-12 g_item\"><div class=\"grid_item kt_item_fade_in kad_gallery_fade_in gallery_item\"><a href=\"https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/IMG_57641-scaled.jpg\" data-rel=\"lightbox\" class=\"lightboxhover\"><div class=\"kt-intrinsic\" style=\"padding-bottom:66.666666666667%;\"><div itemprop=\"image\" itemscope itemtype=\"https:\/\/schema.org\/ImageObject\"><img loading=\"lazy\" decoding=\"async\" width=\"366\" height=\"244\" src=\"https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/IMG_57641-366x244.jpg\" srcset=\"https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/IMG_57641-366x244.jpg 366w, https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/IMG_57641-300x200.jpg 300w, https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/IMG_57641-1024x682.jpg 1024w, https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/IMG_57641-272x182.jpg 272w, https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/IMG_57641-732x488.jpg 732w\" sizes=\"auto, (max-width: 366px) 100vw, 366px\" data-caption=\"\" class=\"light-dropshaddow\" itemprop=\"contentUrl\" alt=\"\"><meta itemprop=\"url\" content=\"https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/IMG_57641-366x244.jpg\"><meta itemprop=\"width\" content=\"366px\"><meta itemprop=\"height\" content=\"244px\"><\/div><\/div><\/a><\/div><\/div><div class=\"tcol-lg-4 tcol-md-4 tcol-sm-4 tcol-xs-6 tcol-ss-12 g_item\"><div class=\"grid_item kt_item_fade_in kad_gallery_fade_in gallery_item\"><a href=\"https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/IMG_57901-scaled.jpg\" data-rel=\"lightbox\" class=\"lightboxhover\"><div class=\"kt-intrinsic\" style=\"padding-bottom:66.666666666667%;\"><div itemprop=\"image\" itemscope itemtype=\"https:\/\/schema.org\/ImageObject\"><img loading=\"lazy\" decoding=\"async\" width=\"366\" height=\"244\" src=\"https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/IMG_57901-366x244.jpg\" srcset=\"https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/IMG_57901-366x244.jpg 366w, https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/IMG_57901-300x200.jpg 300w, https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/IMG_57901-1024x682.jpg 1024w, https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/IMG_57901-272x182.jpg 272w, https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/IMG_57901-732x488.jpg 732w\" sizes=\"auto, (max-width: 366px) 100vw, 366px\" data-caption=\"\" class=\"light-dropshaddow\" itemprop=\"contentUrl\" alt=\"\"><meta itemprop=\"url\" content=\"https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/IMG_57901-366x244.jpg\"><meta itemprop=\"width\" content=\"366px\"><meta itemprop=\"height\" content=\"244px\"><\/div><\/div><\/a><\/div><\/div><div class=\"tcol-lg-4 tcol-md-4 tcol-sm-4 tcol-xs-6 tcol-ss-12 g_item\"><div class=\"grid_item kt_item_fade_in kad_gallery_fade_in gallery_item\"><a href=\"https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/IMG_57761-scaled.jpg\" data-rel=\"lightbox\" class=\"lightboxhover\"><div class=\"kt-intrinsic\" style=\"padding-bottom:66.666666666667%;\"><div itemprop=\"image\" itemscope itemtype=\"https:\/\/schema.org\/ImageObject\"><img loading=\"lazy\" decoding=\"async\" width=\"366\" height=\"244\" src=\"https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/IMG_57761-366x244.jpg\" srcset=\"https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/IMG_57761-366x244.jpg 366w, https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/IMG_57761-300x200.jpg 300w, https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/IMG_57761-1024x682.jpg 1024w, https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/IMG_57761-272x182.jpg 272w, https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/IMG_57761-732x488.jpg 732w\" sizes=\"auto, (max-width: 366px) 100vw, 366px\" data-caption=\"\" class=\"light-dropshaddow\" itemprop=\"contentUrl\" alt=\"\"><meta itemprop=\"url\" content=\"https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/IMG_57761-366x244.jpg\"><meta itemprop=\"width\" content=\"366px\"><meta itemprop=\"height\" content=\"244px\"><\/div><\/div><\/a><\/div><\/div><div class=\"tcol-lg-4 tcol-md-4 tcol-sm-4 tcol-xs-6 tcol-ss-12 g_item\"><div class=\"grid_item kt_item_fade_in kad_gallery_fade_in gallery_item\"><a href=\"https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/IMG_57731-scaled.jpg\" data-rel=\"lightbox\" class=\"lightboxhover\"><div class=\"kt-intrinsic\" style=\"padding-bottom:66.666666666667%;\"><div itemprop=\"image\" itemscope itemtype=\"https:\/\/schema.org\/ImageObject\"><img loading=\"lazy\" decoding=\"async\" width=\"366\" height=\"244\" src=\"https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/IMG_57731-366x244.jpg\" srcset=\"https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/IMG_57731-366x244.jpg 366w, https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/IMG_57731-300x200.jpg 300w, https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/IMG_57731-1024x682.jpg 1024w, https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/IMG_57731-272x182.jpg 272w, https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/IMG_57731-732x488.jpg 732w\" sizes=\"auto, (max-width: 366px) 100vw, 366px\" data-caption=\"\" class=\"light-dropshaddow\" itemprop=\"contentUrl\" alt=\"\"><meta itemprop=\"url\" content=\"https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/IMG_57731-366x244.jpg\"><meta itemprop=\"width\" content=\"366px\"><meta itemprop=\"height\" content=\"244px\"><\/div><\/div><\/a><\/div><\/div><div class=\"tcol-lg-4 tcol-md-4 tcol-sm-4 tcol-xs-6 tcol-ss-12 g_item\"><div class=\"grid_item kt_item_fade_in kad_gallery_fade_in gallery_item\"><a href=\"https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/IMG_57691-scaled.jpg\" data-rel=\"lightbox\" class=\"lightboxhover\"><div class=\"kt-intrinsic\" style=\"padding-bottom:66.666666666667%;\"><div itemprop=\"image\" itemscope itemtype=\"https:\/\/schema.org\/ImageObject\"><img loading=\"lazy\" decoding=\"async\" width=\"366\" height=\"244\" src=\"https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/IMG_57691-366x244.jpg\" srcset=\"https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/IMG_57691-366x244.jpg 366w, https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/IMG_57691-300x200.jpg 300w, https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/IMG_57691-1024x682.jpg 1024w, https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/IMG_57691-272x182.jpg 272w, https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/IMG_57691-732x488.jpg 732w\" sizes=\"auto, (max-width: 366px) 100vw, 366px\" data-caption=\"\" class=\"light-dropshaddow\" itemprop=\"contentUrl\" alt=\"\"><meta itemprop=\"url\" content=\"https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/IMG_57691-366x244.jpg\"><meta itemprop=\"width\" content=\"366px\"><meta itemprop=\"height\" content=\"244px\"><\/div><\/div><\/a><\/div><\/div><div class=\"tcol-lg-4 tcol-md-4 tcol-sm-4 tcol-xs-6 tcol-ss-12 g_item\"><div class=\"grid_item kt_item_fade_in kad_gallery_fade_in gallery_item\"><a href=\"https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/IMG_58021-scaled.jpg\" data-rel=\"lightbox\" class=\"lightboxhover\"><div class=\"kt-intrinsic\" style=\"padding-bottom:66.666666666667%;\"><div itemprop=\"image\" itemscope itemtype=\"https:\/\/schema.org\/ImageObject\"><img loading=\"lazy\" decoding=\"async\" width=\"366\" height=\"244\" src=\"https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/IMG_58021-366x244.jpg\" srcset=\"https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/IMG_58021-366x244.jpg 366w, https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/IMG_58021-300x200.jpg 300w, https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/IMG_58021-1024x682.jpg 1024w, https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/IMG_58021-272x182.jpg 272w, https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/IMG_58021-732x488.jpg 732w\" sizes=\"auto, (max-width: 366px) 100vw, 366px\" data-caption=\"\" class=\"light-dropshaddow\" itemprop=\"contentUrl\" alt=\"\"><meta itemprop=\"url\" content=\"https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/IMG_58021-366x244.jpg\"><meta itemprop=\"width\" content=\"366px\"><meta itemprop=\"height\" content=\"244px\"><\/div><\/div><\/a><\/div><\/div><div class=\"tcol-lg-4 tcol-md-4 tcol-sm-4 tcol-xs-6 tcol-ss-12 g_item\"><div class=\"grid_item kt_item_fade_in kad_gallery_fade_in gallery_item\"><a href=\"https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/IMG_58031-scaled.jpg\" data-rel=\"lightbox\" class=\"lightboxhover\"><div class=\"kt-intrinsic\" style=\"padding-bottom:66.666666666667%;\"><div itemprop=\"image\" itemscope itemtype=\"https:\/\/schema.org\/ImageObject\"><img loading=\"lazy\" decoding=\"async\" width=\"366\" height=\"244\" src=\"https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/IMG_58031-366x244.jpg\" srcset=\"https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/IMG_58031-366x244.jpg 366w, https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/IMG_58031-300x200.jpg 300w, https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/IMG_58031-1024x682.jpg 1024w, https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/IMG_58031-272x182.jpg 272w, https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/IMG_58031-732x488.jpg 732w\" sizes=\"auto, (max-width: 366px) 100vw, 366px\" data-caption=\"\" class=\"light-dropshaddow\" itemprop=\"contentUrl\" alt=\"\"><meta itemprop=\"url\" content=\"https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/IMG_58031-366x244.jpg\"><meta itemprop=\"width\" content=\"366px\"><meta itemprop=\"height\" content=\"244px\"><\/div><\/div><\/a><\/div><\/div><div class=\"tcol-lg-4 tcol-md-4 tcol-sm-4 tcol-xs-6 tcol-ss-12 g_item\"><div class=\"grid_item kt_item_fade_in kad_gallery_fade_in gallery_item\"><a href=\"https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/IMG_58081-scaled.jpg\" data-rel=\"lightbox\" class=\"lightboxhover\"><div class=\"kt-intrinsic\" style=\"padding-bottom:66.666666666667%;\"><div itemprop=\"image\" itemscope itemtype=\"https:\/\/schema.org\/ImageObject\"><img loading=\"lazy\" decoding=\"async\" width=\"366\" height=\"244\" src=\"https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/IMG_58081-366x244.jpg\" srcset=\"https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/IMG_58081-366x244.jpg 366w, https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/IMG_58081-300x200.jpg 300w, https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/IMG_58081-1024x682.jpg 1024w, https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/IMG_58081-272x182.jpg 272w, https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/IMG_58081-732x488.jpg 732w\" sizes=\"auto, (max-width: 366px) 100vw, 366px\" data-caption=\"\" class=\"light-dropshaddow\" itemprop=\"contentUrl\" alt=\"\"><meta itemprop=\"url\" content=\"https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/IMG_58081-366x244.jpg\"><meta itemprop=\"width\" content=\"366px\"><meta itemprop=\"height\" content=\"244px\"><\/div><\/div><\/a><\/div><\/div><div class=\"tcol-lg-4 tcol-md-4 tcol-sm-4 tcol-xs-6 tcol-ss-12 g_item\"><div class=\"grid_item kt_item_fade_in kad_gallery_fade_in gallery_item\"><a href=\"https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/IMG_58101-scaled.jpg\" data-rel=\"lightbox\" class=\"lightboxhover\"><div class=\"kt-intrinsic\" style=\"padding-bottom:150.27322404372%;\"><div itemprop=\"image\" itemscope itemtype=\"https:\/\/schema.org\/ImageObject\"><img loading=\"lazy\" decoding=\"async\" width=\"366\" height=\"550\" src=\"https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/IMG_58101-366x550.jpg\" srcset=\"https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/IMG_58101-366x550.jpg 366w, https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/IMG_58101-200x300.jpg 200w, https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/IMG_58101-682x1024.jpg 682w, https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/IMG_58101-732x1100.jpg 732w, https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/IMG_58101-scaled.jpg 1705w\" sizes=\"auto, (max-width: 366px) 100vw, 366px\" data-caption=\"\" class=\"light-dropshaddow\" itemprop=\"contentUrl\" alt=\"\"><meta itemprop=\"url\" content=\"https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/IMG_58101-366x550.jpg\"><meta itemprop=\"width\" content=\"366px\"><meta itemprop=\"height\" content=\"550px\"><\/div><\/div><\/a><\/div><\/div><div class=\"tcol-lg-4 tcol-md-4 tcol-sm-4 tcol-xs-6 tcol-ss-12 g_item\"><div class=\"grid_item kt_item_fade_in kad_gallery_fade_in gallery_item\"><a href=\"https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/IMG_58141-scaled.jpg\" data-rel=\"lightbox\" class=\"lightboxhover\"><div class=\"kt-intrinsic\" style=\"padding-bottom:150.27322404372%;\"><div itemprop=\"image\" itemscope itemtype=\"https:\/\/schema.org\/ImageObject\"><img loading=\"lazy\" decoding=\"async\" width=\"366\" height=\"550\" src=\"https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/IMG_58141-366x550.jpg\" srcset=\"https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/IMG_58141-366x550.jpg 366w, https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/IMG_58141-200x300.jpg 200w, https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/IMG_58141-682x1024.jpg 682w, https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/IMG_58141-732x1100.jpg 732w, https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/IMG_58141-scaled.jpg 1705w\" sizes=\"auto, (max-width: 366px) 100vw, 366px\" data-caption=\"\" class=\"light-dropshaddow\" itemprop=\"contentUrl\" alt=\"\"><meta itemprop=\"url\" content=\"https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/IMG_58141-366x550.jpg\"><meta itemprop=\"width\" content=\"366px\"><meta itemprop=\"height\" content=\"550px\"><\/div><\/div><\/a><\/div><\/div><div class=\"tcol-lg-4 tcol-md-4 tcol-sm-4 tcol-xs-6 tcol-ss-12 g_item\"><div class=\"grid_item kt_item_fade_in kad_gallery_fade_in gallery_item\"><a href=\"https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/IMG_58131-scaled.jpg\" data-rel=\"lightbox\" class=\"lightboxhover\"><div class=\"kt-intrinsic\" style=\"padding-bottom:150.27322404372%;\"><div itemprop=\"image\" itemscope itemtype=\"https:\/\/schema.org\/ImageObject\"><img loading=\"lazy\" decoding=\"async\" width=\"366\" height=\"550\" src=\"https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/IMG_58131-366x550.jpg\" srcset=\"https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/IMG_58131-366x550.jpg 366w, https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/IMG_58131-200x300.jpg 200w, https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/IMG_58131-682x1024.jpg 682w, https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/IMG_58131-732x1100.jpg 732w, https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/IMG_58131-scaled.jpg 1705w\" sizes=\"auto, (max-width: 366px) 100vw, 366px\" data-caption=\"\" class=\"light-dropshaddow\" itemprop=\"contentUrl\" alt=\"\"><meta itemprop=\"url\" content=\"https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/IMG_58131-366x550.jpg\"><meta itemprop=\"width\" content=\"366px\"><meta itemprop=\"height\" content=\"550px\"><\/div><\/div><\/a><\/div><\/div><div class=\"tcol-lg-4 tcol-md-4 tcol-sm-4 tcol-xs-6 tcol-ss-12 g_item\"><div class=\"grid_item kt_item_fade_in kad_gallery_fade_in gallery_item\"><a href=\"https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/IMG_58121-scaled.jpg\" data-rel=\"lightbox\" class=\"lightboxhover\"><div class=\"kt-intrinsic\" style=\"padding-bottom:150.27322404372%;\"><div itemprop=\"image\" itemscope itemtype=\"https:\/\/schema.org\/ImageObject\"><img loading=\"lazy\" decoding=\"async\" width=\"366\" height=\"550\" src=\"https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/IMG_58121-366x550.jpg\" srcset=\"https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/IMG_58121-366x550.jpg 366w, https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/IMG_58121-200x300.jpg 200w, https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/IMG_58121-682x1024.jpg 682w, https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/IMG_58121-732x1100.jpg 732w, https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/IMG_58121-scaled.jpg 1705w\" sizes=\"auto, (max-width: 366px) 100vw, 366px\" data-caption=\"\" class=\"light-dropshaddow\" itemprop=\"contentUrl\" alt=\"\"><meta itemprop=\"url\" content=\"https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/IMG_58121-366x550.jpg\"><meta itemprop=\"width\" content=\"366px\"><meta itemprop=\"height\" content=\"550px\"><\/div><\/div><\/a><\/div><\/div><div class=\"tcol-lg-4 tcol-md-4 tcol-sm-4 tcol-xs-6 tcol-ss-12 g_item\"><div class=\"grid_item kt_item_fade_in kad_gallery_fade_in gallery_item\"><a href=\"https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/IMG_58111-scaled.jpg\" data-rel=\"lightbox\" class=\"lightboxhover\"><div class=\"kt-intrinsic\" style=\"padding-bottom:66.666666666667%;\"><div itemprop=\"image\" itemscope itemtype=\"https:\/\/schema.org\/ImageObject\"><img loading=\"lazy\" decoding=\"async\" width=\"366\" height=\"244\" src=\"https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/IMG_58111-366x244.jpg\" srcset=\"https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/IMG_58111-366x244.jpg 366w, https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/IMG_58111-300x200.jpg 300w, https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/IMG_58111-1024x682.jpg 1024w, https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/IMG_58111-272x182.jpg 272w, https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/IMG_58111-732x488.jpg 732w\" sizes=\"auto, (max-width: 366px) 100vw, 366px\" data-caption=\"\" class=\"light-dropshaddow\" itemprop=\"contentUrl\" alt=\"\"><meta itemprop=\"url\" content=\"https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/IMG_58111-366x244.jpg\"><meta itemprop=\"width\" content=\"366px\"><meta itemprop=\"height\" content=\"244px\"><\/div><\/div><\/a><\/div><\/div><div class=\"tcol-lg-4 tcol-md-4 tcol-sm-4 tcol-xs-6 tcol-ss-12 g_item\"><div class=\"grid_item kt_item_fade_in kad_gallery_fade_in gallery_item\"><a href=\"https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/IMG_58191-scaled.jpg\" data-rel=\"lightbox\" class=\"lightboxhover\"><div class=\"kt-intrinsic\" style=\"padding-bottom:66.666666666667%;\"><div itemprop=\"image\" itemscope itemtype=\"https:\/\/schema.org\/ImageObject\"><img loading=\"lazy\" decoding=\"async\" width=\"366\" height=\"244\" src=\"https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/IMG_58191-366x244.jpg\" srcset=\"https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/IMG_58191-366x244.jpg 366w, https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/IMG_58191-300x200.jpg 300w, https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/IMG_58191-1024x682.jpg 1024w, https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/IMG_58191-272x182.jpg 272w, https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/IMG_58191-732x488.jpg 732w\" sizes=\"auto, (max-width: 366px) 100vw, 366px\" data-caption=\"\" class=\"light-dropshaddow\" itemprop=\"contentUrl\" alt=\"\"><meta itemprop=\"url\" content=\"https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/IMG_58191-366x244.jpg\"><meta itemprop=\"width\" content=\"366px\"><meta itemprop=\"height\" content=\"244px\"><\/div><\/div><\/a><\/div><\/div><div class=\"tcol-lg-4 tcol-md-4 tcol-sm-4 tcol-xs-6 tcol-ss-12 g_item\"><div class=\"grid_item kt_item_fade_in kad_gallery_fade_in gallery_item\"><a href=\"https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/IMG_58211-scaled.jpg\" data-rel=\"lightbox\" class=\"lightboxhover\"><div class=\"kt-intrinsic\" style=\"padding-bottom:66.666666666667%;\"><div itemprop=\"image\" itemscope itemtype=\"https:\/\/schema.org\/ImageObject\"><img loading=\"lazy\" decoding=\"async\" width=\"366\" height=\"244\" src=\"https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/IMG_58211-366x244.jpg\" srcset=\"https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/IMG_58211-366x244.jpg 366w, https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/IMG_58211-300x200.jpg 300w, https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/IMG_58211-1024x682.jpg 1024w, https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/IMG_58211-272x182.jpg 272w, https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/IMG_58211-732x488.jpg 732w\" sizes=\"auto, (max-width: 366px) 100vw, 366px\" data-caption=\"\" class=\"light-dropshaddow\" itemprop=\"contentUrl\" alt=\"\"><meta itemprop=\"url\" content=\"https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/IMG_58211-366x244.jpg\"><meta itemprop=\"width\" content=\"366px\"><meta itemprop=\"height\" content=\"244px\"><\/div><\/div><\/a><\/div><\/div><div class=\"tcol-lg-4 tcol-md-4 tcol-sm-4 tcol-xs-6 tcol-ss-12 g_item\"><div class=\"grid_item kt_item_fade_in kad_gallery_fade_in gallery_item\"><a href=\"https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/IMG_58251-scaled.jpg\" data-rel=\"lightbox\" class=\"lightboxhover\"><div class=\"kt-intrinsic\" style=\"padding-bottom:66.666666666667%;\"><div itemprop=\"image\" itemscope itemtype=\"https:\/\/schema.org\/ImageObject\"><img loading=\"lazy\" decoding=\"async\" width=\"366\" height=\"244\" src=\"https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/IMG_58251-366x244.jpg\" srcset=\"https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/IMG_58251-366x244.jpg 366w, https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/IMG_58251-300x200.jpg 300w, https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/IMG_58251-1024x682.jpg 1024w, https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/IMG_58251-272x182.jpg 272w, https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/IMG_58251-732x488.jpg 732w\" sizes=\"auto, (max-width: 366px) 100vw, 366px\" data-caption=\"\" class=\"light-dropshaddow\" itemprop=\"contentUrl\" alt=\"\"><meta itemprop=\"url\" content=\"https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/IMG_58251-366x244.jpg\"><meta itemprop=\"width\" content=\"366px\"><meta itemprop=\"height\" content=\"244px\"><\/div><\/div><\/a><\/div><\/div><div class=\"tcol-lg-4 tcol-md-4 tcol-sm-4 tcol-xs-6 tcol-ss-12 g_item\"><div class=\"grid_item kt_item_fade_in kad_gallery_fade_in gallery_item\"><a href=\"https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/IMG_58321-scaled.jpg\" data-rel=\"lightbox\" class=\"lightboxhover\"><div class=\"kt-intrinsic\" style=\"padding-bottom:66.666666666667%;\"><div itemprop=\"image\" itemscope itemtype=\"https:\/\/schema.org\/ImageObject\"><img loading=\"lazy\" decoding=\"async\" width=\"366\" height=\"244\" src=\"https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/IMG_58321-366x244.jpg\" srcset=\"https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/IMG_58321-366x244.jpg 366w, https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/IMG_58321-300x200.jpg 300w, https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/IMG_58321-1024x682.jpg 1024w, https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/IMG_58321-272x182.jpg 272w, https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/IMG_58321-732x488.jpg 732w\" sizes=\"auto, (max-width: 366px) 100vw, 366px\" data-caption=\"\" class=\"light-dropshaddow\" itemprop=\"contentUrl\" alt=\"\"><meta itemprop=\"url\" content=\"https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/IMG_58321-366x244.jpg\"><meta itemprop=\"width\" content=\"366px\"><meta itemprop=\"height\" content=\"244px\"><\/div><\/div><\/a><\/div><\/div><div class=\"tcol-lg-4 tcol-md-4 tcol-sm-4 tcol-xs-6 tcol-ss-12 g_item\"><div class=\"grid_item kt_item_fade_in kad_gallery_fade_in gallery_item\"><a href=\"https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/IMG_58311-scaled.jpg\" data-rel=\"lightbox\" class=\"lightboxhover\"><div class=\"kt-intrinsic\" style=\"padding-bottom:150.27322404372%;\"><div itemprop=\"image\" itemscope itemtype=\"https:\/\/schema.org\/ImageObject\"><img loading=\"lazy\" decoding=\"async\" width=\"366\" height=\"550\" src=\"https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/IMG_58311-366x550.jpg\" srcset=\"https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/IMG_58311-366x550.jpg 366w, https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/IMG_58311-200x300.jpg 200w, https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/IMG_58311-682x1024.jpg 682w, https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/IMG_58311-732x1100.jpg 732w, https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/IMG_58311-scaled.jpg 1705w\" sizes=\"auto, (max-width: 366px) 100vw, 366px\" data-caption=\"\" class=\"light-dropshaddow\" itemprop=\"contentUrl\" alt=\"\"><meta itemprop=\"url\" content=\"https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/IMG_58311-366x550.jpg\"><meta itemprop=\"width\" content=\"366px\"><meta itemprop=\"height\" content=\"550px\"><\/div><\/div><\/a><\/div><\/div><div class=\"tcol-lg-4 tcol-md-4 tcol-sm-4 tcol-xs-6 tcol-ss-12 g_item\"><div class=\"grid_item kt_item_fade_in kad_gallery_fade_in gallery_item\"><a href=\"https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/IMG_58331-scaled.jpg\" data-rel=\"lightbox\" class=\"lightboxhover\"><div class=\"kt-intrinsic\" style=\"padding-bottom:150.27322404372%;\"><div itemprop=\"image\" itemscope itemtype=\"https:\/\/schema.org\/ImageObject\"><img loading=\"lazy\" decoding=\"async\" width=\"366\" height=\"550\" src=\"https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/IMG_58331-366x550.jpg\" srcset=\"https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/IMG_58331-366x550.jpg 366w, https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/IMG_58331-200x300.jpg 200w, https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/IMG_58331-682x1024.jpg 682w, https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/IMG_58331-732x1100.jpg 732w, https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/IMG_58331-scaled.jpg 1705w\" sizes=\"auto, (max-width: 366px) 100vw, 366px\" data-caption=\"\" class=\"light-dropshaddow\" itemprop=\"contentUrl\" alt=\"\"><meta itemprop=\"url\" content=\"https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/IMG_58331-366x550.jpg\"><meta itemprop=\"width\" content=\"366px\"><meta itemprop=\"height\" content=\"550px\"><\/div><\/div><\/a><\/div><\/div><div class=\"tcol-lg-4 tcol-md-4 tcol-sm-4 tcol-xs-6 tcol-ss-12 g_item\"><div class=\"grid_item kt_item_fade_in kad_gallery_fade_in gallery_item\"><a href=\"https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/IMG_58341-scaled.jpg\" data-rel=\"lightbox\" class=\"lightboxhover\"><div class=\"kt-intrinsic\" style=\"padding-bottom:150.27322404372%;\"><div itemprop=\"image\" itemscope itemtype=\"https:\/\/schema.org\/ImageObject\"><img loading=\"lazy\" decoding=\"async\" width=\"366\" height=\"550\" src=\"https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/IMG_58341-366x550.jpg\" srcset=\"https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/IMG_58341-366x550.jpg 366w, https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/IMG_58341-200x300.jpg 200w, https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/IMG_58341-682x1024.jpg 682w, https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/IMG_58341-732x1100.jpg 732w, https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/IMG_58341-scaled.jpg 1705w\" sizes=\"auto, (max-width: 366px) 100vw, 366px\" data-caption=\"\" class=\"light-dropshaddow\" itemprop=\"contentUrl\" alt=\"\"><meta itemprop=\"url\" content=\"https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/IMG_58341-366x550.jpg\"><meta itemprop=\"width\" content=\"366px\"><meta itemprop=\"height\" content=\"550px\"><\/div><\/div><\/a><\/div><\/div><div class=\"tcol-lg-4 tcol-md-4 tcol-sm-4 tcol-xs-6 tcol-ss-12 g_item\"><div class=\"grid_item kt_item_fade_in kad_gallery_fade_in gallery_item\"><a href=\"https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/IMG_58351-scaled.jpg\" data-rel=\"lightbox\" class=\"lightboxhover\"><div class=\"kt-intrinsic\" style=\"padding-bottom:150.27322404372%;\"><div itemprop=\"image\" itemscope itemtype=\"https:\/\/schema.org\/ImageObject\"><img loading=\"lazy\" decoding=\"async\" width=\"366\" height=\"550\" src=\"https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/IMG_58351-366x550.jpg\" srcset=\"https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/IMG_58351-366x550.jpg 366w, https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/IMG_58351-200x300.jpg 200w, https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/IMG_58351-682x1024.jpg 682w, https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/IMG_58351-732x1100.jpg 732w, https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/IMG_58351-scaled.jpg 1705w\" sizes=\"auto, (max-width: 366px) 100vw, 366px\" data-caption=\"\" class=\"light-dropshaddow\" itemprop=\"contentUrl\" alt=\"\"><meta itemprop=\"url\" content=\"https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/IMG_58351-366x550.jpg\"><meta itemprop=\"width\" content=\"366px\"><meta itemprop=\"height\" content=\"550px\"><\/div><\/div><\/a><\/div><\/div><div class=\"tcol-lg-4 tcol-md-4 tcol-sm-4 tcol-xs-6 tcol-ss-12 g_item\"><div class=\"grid_item kt_item_fade_in kad_gallery_fade_in gallery_item\"><a href=\"https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/IMG_5839-scaled.jpg\" data-rel=\"lightbox\" class=\"lightboxhover\"><div class=\"kt-intrinsic\" style=\"padding-bottom:66.666666666667%;\"><div itemprop=\"image\" itemscope itemtype=\"https:\/\/schema.org\/ImageObject\"><img loading=\"lazy\" decoding=\"async\" width=\"366\" height=\"244\" src=\"https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/IMG_5839-366x244.jpg\" srcset=\"https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/IMG_5839-366x244.jpg 366w, https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/IMG_5839-300x200.jpg 300w, https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/IMG_5839-1024x682.jpg 1024w, https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/IMG_5839-272x182.jpg 272w, https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/IMG_5839-732x488.jpg 732w\" sizes=\"auto, (max-width: 366px) 100vw, 366px\" data-caption=\"\" class=\"light-dropshaddow\" itemprop=\"contentUrl\" alt=\"\"><meta itemprop=\"url\" content=\"https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/IMG_5839-366x244.jpg\"><meta itemprop=\"width\" content=\"366px\"><meta itemprop=\"height\" content=\"244px\"><\/div><\/div><\/a><\/div><\/div><div class=\"tcol-lg-4 tcol-md-4 tcol-sm-4 tcol-xs-6 tcol-ss-12 g_item\"><div class=\"grid_item kt_item_fade_in kad_gallery_fade_in gallery_item\"><a href=\"https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/IMG_5841-scaled.jpg\" data-rel=\"lightbox\" class=\"lightboxhover\"><div class=\"kt-intrinsic\" style=\"padding-bottom:66.666666666667%;\"><div itemprop=\"image\" itemscope itemtype=\"https:\/\/schema.org\/ImageObject\"><img loading=\"lazy\" decoding=\"async\" width=\"366\" height=\"244\" src=\"https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/IMG_5841-366x244.jpg\" srcset=\"https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/IMG_5841-366x244.jpg 366w, https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/IMG_5841-300x200.jpg 300w, https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/IMG_5841-1024x682.jpg 1024w, https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/IMG_5841-272x182.jpg 272w, https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/IMG_5841-732x488.jpg 732w\" sizes=\"auto, (max-width: 366px) 100vw, 366px\" data-caption=\"\" class=\"light-dropshaddow\" itemprop=\"contentUrl\" alt=\"\"><meta itemprop=\"url\" content=\"https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/IMG_5841-366x244.jpg\"><meta itemprop=\"width\" content=\"366px\"><meta itemprop=\"height\" content=\"244px\"><\/div><\/div><\/a><\/div><\/div><div class=\"tcol-lg-4 tcol-md-4 tcol-sm-4 tcol-xs-6 tcol-ss-12 g_item\"><div class=\"grid_item kt_item_fade_in kad_gallery_fade_in gallery_item\"><a href=\"https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/IMG_58361-scaled.jpg\" data-rel=\"lightbox\" class=\"lightboxhover\"><div class=\"kt-intrinsic\" style=\"padding-bottom:66.666666666667%;\"><div itemprop=\"image\" itemscope itemtype=\"https:\/\/schema.org\/ImageObject\"><img loading=\"lazy\" decoding=\"async\" width=\"366\" height=\"244\" src=\"https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/IMG_58361-366x244.jpg\" srcset=\"https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/IMG_58361-366x244.jpg 366w, https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/IMG_58361-300x200.jpg 300w, https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/IMG_58361-1024x682.jpg 1024w, https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/IMG_58361-272x182.jpg 272w, https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/IMG_58361-732x488.jpg 732w\" sizes=\"auto, (max-width: 366px) 100vw, 366px\" data-caption=\"\" class=\"light-dropshaddow\" itemprop=\"contentUrl\" alt=\"\"><meta itemprop=\"url\" content=\"https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/IMG_58361-366x244.jpg\"><meta itemprop=\"width\" content=\"366px\"><meta itemprop=\"height\" content=\"244px\"><\/div><\/div><\/a><\/div><\/div><div class=\"tcol-lg-4 tcol-md-4 tcol-sm-4 tcol-xs-6 tcol-ss-12 g_item\"><div class=\"grid_item kt_item_fade_in kad_gallery_fade_in gallery_item\"><a href=\"https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/IMG_5842-scaled.jpg\" data-rel=\"lightbox\" class=\"lightboxhover\"><div class=\"kt-intrinsic\" style=\"padding-bottom:66.666666666667%;\"><div itemprop=\"image\" itemscope itemtype=\"https:\/\/schema.org\/ImageObject\"><img loading=\"lazy\" decoding=\"async\" width=\"366\" height=\"244\" src=\"https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/IMG_5842-366x244.jpg\" srcset=\"https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/IMG_5842-366x244.jpg 366w, https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/IMG_5842-300x200.jpg 300w, https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/IMG_5842-1024x682.jpg 1024w, https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/IMG_5842-272x182.jpg 272w, https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/IMG_5842-732x488.jpg 732w\" sizes=\"auto, (max-width: 366px) 100vw, 366px\" data-caption=\"\" class=\"light-dropshaddow\" itemprop=\"contentUrl\" alt=\"\"><meta itemprop=\"url\" content=\"https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/IMG_5842-366x244.jpg\"><meta itemprop=\"width\" content=\"366px\"><meta itemprop=\"height\" content=\"244px\"><\/div><\/div><\/a><\/div><\/div><div class=\"tcol-lg-4 tcol-md-4 tcol-sm-4 tcol-xs-6 tcol-ss-12 g_item\"><div class=\"grid_item kt_item_fade_in kad_gallery_fade_in gallery_item\"><a href=\"https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/IMG_5844-scaled.jpg\" data-rel=\"lightbox\" class=\"lightboxhover\"><div class=\"kt-intrinsic\" style=\"padding-bottom:150.27322404372%;\"><div itemprop=\"image\" itemscope itemtype=\"https:\/\/schema.org\/ImageObject\"><img loading=\"lazy\" decoding=\"async\" width=\"366\" height=\"550\" src=\"https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/IMG_5844-366x550.jpg\" srcset=\"https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/IMG_5844-366x550.jpg 366w, https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/IMG_5844-200x300.jpg 200w, https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/IMG_5844-682x1024.jpg 682w, https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/IMG_5844-732x1100.jpg 732w, https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/IMG_5844-scaled.jpg 1705w\" sizes=\"auto, (max-width: 366px) 100vw, 366px\" data-caption=\"\" class=\"light-dropshaddow\" itemprop=\"contentUrl\" alt=\"\"><meta itemprop=\"url\" content=\"https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/IMG_5844-366x550.jpg\"><meta itemprop=\"width\" content=\"366px\"><meta itemprop=\"height\" content=\"550px\"><\/div><\/div><\/a><\/div><\/div><div class=\"tcol-lg-4 tcol-md-4 tcol-sm-4 tcol-xs-6 tcol-ss-12 g_item\"><div class=\"grid_item kt_item_fade_in kad_gallery_fade_in gallery_item\"><a href=\"https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/IMG_5847-scaled.jpg\" data-rel=\"lightbox\" class=\"lightboxhover\"><div class=\"kt-intrinsic\" style=\"padding-bottom:150.27322404372%;\"><div itemprop=\"image\" itemscope itemtype=\"https:\/\/schema.org\/ImageObject\"><img loading=\"lazy\" decoding=\"async\" width=\"366\" height=\"550\" src=\"https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/IMG_5847-366x550.jpg\" srcset=\"https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/IMG_5847-366x550.jpg 366w, https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/IMG_5847-200x300.jpg 200w, https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/IMG_5847-682x1024.jpg 682w, https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/IMG_5847-732x1100.jpg 732w, https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/IMG_5847-scaled.jpg 1705w\" sizes=\"auto, (max-width: 366px) 100vw, 366px\" data-caption=\"\" class=\"light-dropshaddow\" itemprop=\"contentUrl\" alt=\"\"><meta itemprop=\"url\" content=\"https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/IMG_5847-366x550.jpg\"><meta itemprop=\"width\" content=\"366px\"><meta itemprop=\"height\" content=\"550px\"><\/div><\/div><\/a><\/div><\/div><div class=\"tcol-lg-4 tcol-md-4 tcol-sm-4 tcol-xs-6 tcol-ss-12 g_item\"><div class=\"grid_item kt_item_fade_in kad_gallery_fade_in gallery_item\"><a href=\"https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/IMG_5849-scaled.jpg\" data-rel=\"lightbox\" class=\"lightboxhover\"><div class=\"kt-intrinsic\" style=\"padding-bottom:150.27322404372%;\"><div itemprop=\"image\" itemscope itemtype=\"https:\/\/schema.org\/ImageObject\"><img loading=\"lazy\" decoding=\"async\" width=\"366\" height=\"550\" src=\"https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/IMG_5849-366x550.jpg\" srcset=\"https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/IMG_5849-366x550.jpg 366w, https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/IMG_5849-200x300.jpg 200w, https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/IMG_5849-682x1024.jpg 682w, https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/IMG_5849-732x1100.jpg 732w, https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/IMG_5849-scaled.jpg 1705w\" sizes=\"auto, (max-width: 366px) 100vw, 366px\" data-caption=\"\" class=\"light-dropshaddow\" itemprop=\"contentUrl\" alt=\"\"><meta itemprop=\"url\" content=\"https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/IMG_5849-366x550.jpg\"><meta itemprop=\"width\" content=\"366px\"><meta itemprop=\"height\" content=\"550px\"><\/div><\/div><\/a><\/div><\/div><div class=\"tcol-lg-4 tcol-md-4 tcol-sm-4 tcol-xs-6 tcol-ss-12 g_item\"><div class=\"grid_item kt_item_fade_in kad_gallery_fade_in gallery_item\"><a href=\"https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/IMG_5852-scaled.jpg\" data-rel=\"lightbox\" class=\"lightboxhover\"><div class=\"kt-intrinsic\" style=\"padding-bottom:150.27322404372%;\"><div itemprop=\"image\" itemscope itemtype=\"https:\/\/schema.org\/ImageObject\"><img loading=\"lazy\" decoding=\"async\" width=\"366\" height=\"550\" src=\"https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/IMG_5852-366x550.jpg\" srcset=\"https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/IMG_5852-366x550.jpg 366w, https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/IMG_5852-200x300.jpg 200w, https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/IMG_5852-682x1024.jpg 682w, https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/IMG_5852-732x1100.jpg 732w, https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/IMG_5852-scaled.jpg 1705w\" sizes=\"auto, (max-width: 366px) 100vw, 366px\" data-caption=\"\" class=\"light-dropshaddow\" itemprop=\"contentUrl\" alt=\"\"><meta itemprop=\"url\" content=\"https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/IMG_5852-366x550.jpg\"><meta itemprop=\"width\" content=\"366px\"><meta itemprop=\"height\" content=\"550px\"><\/div><\/div><\/a><\/div><\/div><div class=\"tcol-lg-4 tcol-md-4 tcol-sm-4 tcol-xs-6 tcol-ss-12 g_item\"><div class=\"grid_item kt_item_fade_in kad_gallery_fade_in gallery_item\"><a href=\"https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/IMG_5854-scaled.jpg\" data-rel=\"lightbox\" class=\"lightboxhover\"><div class=\"kt-intrinsic\" style=\"padding-bottom:66.666666666667%;\"><div itemprop=\"image\" itemscope itemtype=\"https:\/\/schema.org\/ImageObject\"><img loading=\"lazy\" decoding=\"async\" width=\"366\" height=\"244\" src=\"https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/IMG_5854-366x244.jpg\" srcset=\"https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/IMG_5854-366x244.jpg 366w, https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/IMG_5854-300x200.jpg 300w, https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/IMG_5854-1024x682.jpg 1024w, https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/IMG_5854-272x182.jpg 272w, https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/IMG_5854-732x488.jpg 732w\" sizes=\"auto, (max-width: 366px) 100vw, 366px\" data-caption=\"\" class=\"light-dropshaddow\" itemprop=\"contentUrl\" alt=\"\"><meta itemprop=\"url\" content=\"https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/IMG_5854-366x244.jpg\"><meta itemprop=\"width\" content=\"366px\"><meta itemprop=\"height\" content=\"244px\"><\/div><\/div><\/a><\/div><\/div><div class=\"tcol-lg-4 tcol-md-4 tcol-sm-4 tcol-xs-6 tcol-ss-12 g_item\"><div class=\"grid_item kt_item_fade_in kad_gallery_fade_in gallery_item\"><a href=\"https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/IMG_5855-scaled.jpg\" data-rel=\"lightbox\" class=\"lightboxhover\"><div class=\"kt-intrinsic\" style=\"padding-bottom:66.666666666667%;\"><div itemprop=\"image\" itemscope itemtype=\"https:\/\/schema.org\/ImageObject\"><img loading=\"lazy\" decoding=\"async\" width=\"366\" height=\"244\" src=\"https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/IMG_5855-366x244.jpg\" srcset=\"https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/IMG_5855-366x244.jpg 366w, https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/IMG_5855-300x200.jpg 300w, https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/IMG_5855-1024x682.jpg 1024w, https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/IMG_5855-272x182.jpg 272w, https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/IMG_5855-732x488.jpg 732w\" sizes=\"auto, (max-width: 366px) 100vw, 366px\" data-caption=\"\" class=\"light-dropshaddow\" itemprop=\"contentUrl\" alt=\"\"><meta itemprop=\"url\" content=\"https:\/\/nmcontemporaneo.com\/wp-content\/uploads\/2015\/05\/IMG_5855-366x244.jpg\"><meta itemprop=\"width\" content=\"366px\"><meta itemprop=\"height\" content=\"244px\"><\/div><\/div><\/a><\/div><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>De la forma a la funci\u00f3n. Cuernavaca, Morelos. La galer\u00eda NM Contempor\u00e1neo presenta la exposici\u00f3n De la forma a la funci\u00f3n, producida por el artista multidisciplinario y fil\u00f3sofo mexicano Nacho Rodriguez Bach (Ciudad de M\u00e9xico, 1966). Especializado en medios electr\u00f3nicos, &hellip; <a class=\"kt-excerpt-readmore\" href=\"https:\/\/nmcontemporaneo.com\/en\/de-la-forma-a-la-funcion-2014\/\" aria-label=\"\">Read More<\/a><\/p>\n","protected":false},"author":25,"featured_media":7116,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"kt_blocks_editor_width":"","footnotes":""},"categories":[51],"tags":[278,279],"class_list":["post-7054","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-exhibitions","tag-de-la-forma-a-la-funcion","tag-nacho-rodriguez-bach"],"_links":{"self":[{"href":"https:\/\/nmcontemporaneo.com\/en\/wp-json\/wp\/v2\/posts\/7054","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nmcontemporaneo.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/nmcontemporaneo.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/nmcontemporaneo.com\/en\/wp-json\/wp\/v2\/users\/25"}],"replies":[{"embeddable":true,"href":"https:\/\/nmcontemporaneo.com\/en\/wp-json\/wp\/v2\/comments?post=7054"}],"version-history":[{"count":1,"href":"https:\/\/nmcontemporaneo.com\/en\/wp-json\/wp\/v2\/posts\/7054\/revisions"}],"predecessor-version":[{"id":14047,"href":"https:\/\/nmcontemporaneo.com\/en\/wp-json\/wp\/v2\/posts\/7054\/revisions\/14047"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/nmcontemporaneo.com\/en\/wp-json\/wp\/v2\/media\/7116"}],"wp:attachment":[{"href":"https:\/\/nmcontemporaneo.com\/en\/wp-json\/wp\/v2\/media?parent=7054"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/nmcontemporaneo.com\/en\/wp-json\/wp\/v2\/categories?post=7054"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/nmcontemporaneo.com\/en\/wp-json\/wp\/v2\/tags?post=7054"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}